{"id":5742,"date":"2020-02-28T14:05:36","date_gmt":"2020-02-28T13:05:36","guid":{"rendered":"https:\/\/www.zeltwanger.de\/?page_id=5742"},"modified":"2025-09-08T10:44:08","modified_gmt":"2025-09-08T08:44:08","slug":"leckkalibrator","status":"publish","type":"page","link":"https:\/\/www.zeltwanger.de\/de\/technologien\/dichtheitspruefung\/dichtheitspruefung-mit-luft\/leckkalibrator\/","title":{"rendered":"Leckkalibrator"},"content":{"rendered":"<h1>Leckkalibrator<\/h1>\n<h2>F\u00fcr sichere <br \/>Dichtheitspr\u00fcfger\u00e4te<\/h2>\n<div>\n<p class=\"Textbody\">Unser Leckkalibrator dient zur \u00dcberpr\u00fcfung und Parametrierung von Lecktest- und Dichtheitspr\u00fcfger\u00e4ten.<o:p><\/o:p><\/p>\n<p class=\"Textbody\">Hierf\u00fcr wird der Leckkalibrator an die Lecksimulation des Ger\u00e4tes angeschlossen und die gew\u00fcnschte Leckrate \u2013 in Abh\u00e4ngigkeit vom anstehenden Pr\u00fcfdruck \u2013 \u00fcber eine Pr\u00e4zisionsdrossel eingestellt.<o:p><\/o:p><\/p>\n<\/div>\n<p><img decoding=\"async\" src=\"\/app\/uploads\/2020\/02\/ZW_Website-2020_Leckkalibrator_420x337px_R01-1.png\" alt=\"Leckkalibrator von ZELTWANGER\"><\/p>\n<h2>Lieferumfang<\/h2>\n<ul>\n<li>\n<div>1 x ZELTWANGER Leckkalibrator\n<\/div>\n<\/li>\n<li>\n<div> 1 x Kunststoffkoffer mit Formeinsatz\n<\/div>\n<\/li>\n<li>\n<div> 1 x Netzteil\n<\/div>\n<\/li>\n<li>\n<div> 2 x Batterie AA Mignon\n<\/div>\n<\/li>\n<li>\n<div> 1 x Pr\u00fcfschlauch inkl. Kupplungen\n<\/div>\n<\/li>\n<li>\n<div> 1 x Pr\u00fcfzertifikat (Werkskalibrierung)\n<\/div>\n<\/li>\n<li>\n<div> Optional: DAkkS-Kalibrierung\n<\/div>\n<\/li>\n<\/ul>\n<h2>Zubeh\u00f6r<\/h2>\n<div>\n<div>1 x Schnittstellenkabel <br \/>RS232 SUB D9 5 m<\/div>\n<\/div>\n<h2>Messmittel\u00fcberwachung<\/h2>\n<div>Wir empfehlen eine j\u00e4hrliche Kalibrierung des Pr\u00fcflecks.<\/div>\n<table>\n<thead>\n<tr>\n<th>Messbereiche:<\/th>\n<th>Bestellnummer:<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<td>200 (20) ml\/min *<\/td>\n<td>118582<\/td>\n<\/tr>\n<tr>\n<td>2000 (200) ml\/min*<\/td>\n<td>118583<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<div>\n<p><strong>* Referenzbedingungen gem\u00e4\u00df DIN1343:<\/strong><br \/><em>T<sub>n<span>\u00a0<\/span><\/sub><\/em><span>= 273,15K (0\u00b0C)<\/span><br \/><em>P<sub>n<\/sub><\/em><span>\u00a0= 101325 Pa (1013,25 mbar absolut)<\/span><\/p>\n<\/div>\n<h2>Technische Daten<\/h2>\n<table>\n<tbody>\n<tr>\n<td>Genauigkeit im Teilbereich:<\/td>\n<td>\n<p>0 \u2013 10 % &lt; 1,5% v.E. (Vom Endwert)(Feineinstellung)<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>Genauigkeit im Teilbereich:<\/td>\n<td>\n<p>10 \u2013 100 % &lt; 1,5% v.E. (Grobeinstellung)<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>Anzeigenaufl\u00f6sung:<\/td>\n<td>\n<p>0,005 % v. E.<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>Temperatureinfluss auf den Messwert:<\/td>\n<td>\n<p>0,1 % v. M.\/\u00b0C (v. M. = Vom Messwert)<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>Maximaler Betriebsdruck:<\/td>\n<td>\n<p>10 bar statisch<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>Maximaler Durchfluss:<\/td>\n<td>\n<p>5.000 Nml \/ min<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>Datenschnittstelle:<\/td>\n<td>\n<p>RS 232 (9-polig)<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>Abmessungen (H x B x T):<\/td>\n<td>\n<p>Leckkalibrator: 40 x 83 x 153 mm<br \/>Kunststoffkoffer: 82 x 275 x 230 mm<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>Gewicht:<\/td>\n<td>\n<p>Leckkalibrator: 0,4 kg<br \/>Kunststoffkoffer: 1,1 kg<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>Stromversorgung:<\/td>\n<td>\n<p>2 x Batterien AA \/ 2 x 1,2 Volt NiMH-Akku \/ 3,3 Volt Weit bereichs-Steckernetzteil (100 \u2013 240 VAC)<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>Druckluftversorgung: <\/td>\n<td>\n<p>\u00d6l- und wasserfreie Druckluft (ISO 8573-1 Klasse 3)<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>Temperaturmessbereich:<\/td>\n<td>\n<p>10 \u00b0C \u2013 40 \u00b0C<\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<div>\n<p>Datenblatt Leckkalibrator<\/p>\n<\/div>\n<p><p>\n        <a href=\"https:\/\/www.zeltwanger.de\/app\/uploads\/2025\/09\/rz_Datenblatt_Leckkalibrator_DE_2025_screen.pdf\">Download (PDF)<\/a>\n    <\/p>\n<\/p>\n<h3>Verwandte Produkte<\/h3>\n<p><a href=\"\/de\/technologien\/dichtheitspruefung\/dichtheitspruefung-mit-luft\/zedcore\/\"><img decoding=\"async\" src=\"\/app\/uploads\/2020\/03\/Zeltwanger_ZEDcore_002_DE_2019-09-23_web.png\" alt=\"\"><\/a><\/p>\n<div>\n<p><a href=\"https:\/\/www.zeltwanger.de\/de\/technologien\/dichtheitspruefung\/dichtheitspruefung-mit-luft\/zedcore\/\">ZEDcore<\/a><\/p>\n<\/div>\n<p><a href=\"\/de\/technologien\/dichtheitspruefung\/dichtheitspruefung-mit-luft\/pruefleck\/\"><img decoding=\"async\" src=\"\/app\/uploads\/2020\/02\/ZW_Website-2020_Pruefleck_420x337px_R01-1.png\" alt=\"\"><\/a><\/p>\n<div>\n<p><a href=\"https:\/\/www.zeltwanger.de\/de\/technologien\/dichtheitspruefung\/dichtheitspruefung-mit-luft\/pruefleck\/\">Pr\u00fcfleck<\/a><\/p>\n<\/div>\n<div>\n<h1><\/h1>\n<p>Option: <\/p>\n<\/div>\n<p><!--more--><br \/>\n<!-- {\"type\":\"layout\",\"children\":[{\"type\":\"section\",\"props\":{\"class\":\"highlight-section\",\"css\":\".el-section { position: relative; }\",\"height\":\"section\",\"height_offset_top\":true,\"image_position\":\"center-center\",\"style\":\"default\",\"title_breakpoint\":\"xl\",\"title_position\":\"top-left\",\"title_rotation\":\"left\",\"vertical_align\":\"middle\",\"width\":\"default\"},\"children\":[{\"type\":\"row\",\"props\":{\"layout\":\"1-2,1-2\"},\"children\":[{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"position_sticky_breakpoint\":\"m\",\"text_color\":\"light\",\"vertical_align\":\"middle\",\"width_medium\":\"1-2\"},\"children\":[{\"type\":\"headline\",\"props\":{\"content\":\"Leckkalibrator\",\"margin\":\"small\",\"margin_remove_bottom\":false,\"margin_remove_top\":true,\"title_element\":\"h1\",\"title_style\":\"heading-small\"}},{\"type\":\"headline\",\"props\":{\"content\":\"F\\u00fcr sichere <br \\\/>Dichtheitspr\\u00fcfger\\u00e4te\",\"margin\":\"medium\",\"margin_remove_top\":true,\"title_element\":\"h2\",\"title_style\":\"heading-large\"}},{\"type\":\"text\",\"props\":{\"column_breakpoint\":\"m\",\"content\":\"\n\n<p class=\\\"Textbody\\\">Unser Leckkalibrator dient zur \\u00dcberpr\\u00fcfung und Parametrierung von Lecktest- und Dichtheitspr\\u00fcfger\\u00e4ten.<o:p><\\\/o:p><\\\/p>\\n\n\n<p class=\\\"Textbody\\\">Hierf\\u00fcr wird der Leckkalibrator an die Lecksimulation des Ger\\u00e4tes angeschlossen und die gew\\u00fcnschte Leckrate \\u2013 in Abh\\u00e4ngigkeit vom anstehenden Pr\\u00fcfdruck \\u2013 \\u00fcber eine Pr\\u00e4zisionsdrossel eingestellt.<o:p><\\\/o:p><\\\/p>\",\"dropcap\":false,\"margin\":\"default\"}}]},{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"position_sticky_breakpoint\":\"m\",\"vertical_align\":\"middle\",\"width_medium\":\"1-2\"},\"children\":[{\"type\":\"image\",\"props\":{\"image\":\"app\\\/uploads\\\/2020\\\/02\\\/ZW_Website-2020_Leckkalibrator_420x337px_R01-1.png\",\"image_alt\":\"Leckkalibrator von ZELTWANGER\",\"image_height\":\"800\",\"image_svg_color\":\"emphasis\",\"margin\":\"default\",\"text_align\":\"center\"}}]}]}],\"name\":\"Intro Bild\"},{\"type\":\"section\",\"props\":{\"class\":\"breadcrumb\",\"image_position\":\"center-center\",\"padding\":\"xsmall\",\"padding_remove_bottom\":true,\"padding_remove_top\":false,\"style\":\"default\",\"title_breakpoint\":\"xl\",\"title_position\":\"top-left\",\"title_rotation\":\"left\",\"vertical_align\":\"\",\"width\":\"default\"},\"children\":[{\"type\":\"row\",\"props\":{\"width\":\"small\"},\"children\":[{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"position_sticky_breakpoint\":\"m\",\"width_medium\":\"1-1\"},\"children\":[{\"type\":\"breadcrumbs\",\"props\":{\"image_svg_color\":\"emphasis\",\"margin\":\"default\"}}]}]}],\"name\":\"Breadcrumb\"},{\"type\":\"section\",\"props\":{\"image_position\":\"center-center\",\"padding_remove_bottom\":true,\"padding_remove_top\":false,\"style\":\"default\",\"title_breakpoint\":\"xl\",\"title_position\":\"top-left\",\"title_rotation\":\"left\",\"vertical_align\":\"\",\"width\":\"small\"},\"children\":[{\"type\":\"row\",\"props\":{\"layout\":\"1-2,1-2\"},\"children\":[{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"position_sticky_breakpoint\":\"m\",\"style\":\"card-default\",\"width_medium\":\"1-2\"},\"children\":[{\"type\":\"headline\",\"props\":{\"content\":\"Lieferumfang\",\"text_align\":\"center\",\"title_color\":\"primary\",\"title_element\":\"h2\",\"title_style\":\"heading-medium\"}},{\"type\":\"list\",\"props\":{\"class\":\"pluslist\",\"column_breakpoint\":\"m\",\"icon_color\":\"primary\",\"image_align\":\"left\",\"image_svg_color\":\"emphasis\",\"image_vertical_align\":true,\"list_element\":\"ul\",\"list_horizontal_separator\":\", \",\"list_type\":\"vertical\",\"show_image\":true,\"show_link\":true},\"children\":[{\"type\":\"list_item\",\"props\":{\"content\":\"1 x ZELTWANGER Leckkalibrator\\n\",\"icon\":\"plus\"}},{\"type\":\"list_item\",\"props\":{\"content\":\" 1 x Kunststoffkoffer mit Formeinsatz\\n\",\"icon\":\"plus\"}},{\"type\":\"list_item\",\"props\":{\"content\":\" 1 x Netzteil\\n\",\"icon\":\"plus\"}},{\"type\":\"list_item\",\"props\":{\"content\":\" 2 x Batterie AA Mignon\\n\",\"icon\":\"plus\"}},{\"type\":\"list_item\",\"props\":{\"content\":\" 1 x Pr\\u00fcfschlauch inkl. Kupplungen\\n\",\"icon\":\"plus\"}},{\"type\":\"list_item\",\"props\":{\"content\":\" 1 x Pr\\u00fcfzertifikat (Werkskalibrierung)\\n\",\"icon\":\"plus\"}},{\"type\":\"list_item\",\"props\":{\"content\":\" Optional: DAkkS-Kalibrierung\\n\",\"icon\":\"plus\"}}],\"name\":\"Plus Liste \"}]},{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"position_sticky_breakpoint\":\"m\",\"style\":\"card-default\",\"width_medium\":\"1-2\"},\"children\":[{\"type\":\"headline\",\"props\":{\"content\":\"Zubeh\\u00f6r\",\"text_align\":\"center\",\"title_color\":\"primary\",\"title_element\":\"h2\",\"title_style\":\"heading-medium\"}},{\"type\":\"list\",\"props\":{\"class\":\"pluslist\",\"column_breakpoint\":\"m\",\"icon_color\":\"primary\",\"image_align\":\"left\",\"image_svg_color\":\"emphasis\",\"image_vertical_align\":true,\"list_element\":\"ul\",\"list_horizontal_separator\":\", \",\"list_type\":\"vertical\",\"show_image\":true,\"show_link\":true},\"children\":[{\"type\":\"list_item\",\"props\":{\"content\":\"1 x Schnittstellenkabel <br \\\/>RS232 SUB D9 5 m\",\"icon\":\"plus\"}}],\"name\":\"Plus Liste \"}]}]}],\"name\":\"Eckdaten\"},{\"type\":\"section\",\"props\":{\"id\":\"technische-daten\",\"image_position\":\"center-center\",\"padding_remove_bottom\":true,\"padding_remove_top\":false,\"style\":\"default\",\"title_breakpoint\":\"xl\",\"title_position\":\"top-left\",\"title_rotation\":\"left\",\"vertical_align\":\"\",\"width\":\"small\"},\"children\":[{\"type\":\"row\",\"props\":{\"layout\":\"1-2,1-2\"},\"children\":[{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"position_sticky_breakpoint\":\"m\",\"width_medium\":\"1-2\"},\"children\":[{\"type\":\"headline\",\"props\":{\"content\":\"Messmittel\\u00fcberwachung\",\"text_align\":\"left\",\"title_color\":\"primary\",\"title_element\":\"h2\",\"title_style\":\"heading-medium\"}},{\"type\":\"text\",\"props\":{\"column_breakpoint\":\"m\",\"content\":\"Wir empfehlen eine j\\u00e4hrliche Kalibrierung des Pr\\u00fcflecks.\",\"margin\":\"default\"}}]},{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"position_sticky_breakpoint\":\"m\",\"width_medium\":\"1-2\"},\"children\":[{\"type\":\"table\",\"props\":{\"image_svg_color\":\"emphasis\",\"link_style\":\"default\",\"link_text\":\"Read more\",\"meta_style\":\"text-meta\",\"show_content\":true,\"show_image\":false,\"show_link\":false,\"show_meta\":false,\"show_title\":true,\"table_head_content\":\"Bestellnummer:\",\"table_head_title\":\"Messbereiche:\",\"table_hover\":false,\"table_justify\":true,\"table_order\":\"1\",\"table_responsive\":\"overflow\",\"table_size\":\"small\",\"table_style\":\"striped\",\"table_width_meta\":\"shrink\",\"table_width_title\":\"shrink\"},\"children\":[{\"type\":\"table_item\",\"props\":{\"content\":\"118582\",\"meta\":\"\",\"title\":\"200 (20) ml\\\/min *\"}},{\"type\":\"table_item\",\"props\":{\"content\":\"118583\",\"meta\":\"\",\"title\":\"2000 (200) ml\\\/min*\"}}]},{\"type\":\"text\",\"props\":{\"column_breakpoint\":\"m\",\"content\":\"\n\n<p><strong>* Referenzbedingungen gem\\u00e4\\u00df DIN1343:<\\\/strong><br \\\/><em>T<sub>n<span>\\u00a0<\\\/span><\\\/sub><\\\/em><span>= 273,15K (0\\u00b0C)<\\\/span><br \\\/><em>P<sub>n<\\\/sub><\\\/em><span>\\u00a0= 101325 Pa (1013,25 mbar absolut)<\\\/span><\\\/p>\",\"margin\":\"default\",\"text_style\":\"small\"}}]}]}],\"name\":\"Daten\"},{\"type\":\"section\",\"props\":{\"id\":\"technische-daten\",\"image_position\":\"center-center\",\"padding_remove_bottom\":true,\"padding_remove_top\":false,\"style\":\"default\",\"title_breakpoint\":\"xl\",\"title_position\":\"top-left\",\"title_rotation\":\"left\",\"vertical_align\":\"\",\"width\":\"small\"},\"children\":[{\"type\":\"row\",\"children\":[{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"position_sticky_breakpoint\":\"m\",\"width_medium\":\"1-1\"},\"children\":[{\"type\":\"headline\",\"props\":{\"content\":\"Technische Daten\",\"text_align\":\"left\",\"title_color\":\"primary\",\"title_element\":\"h2\",\"title_style\":\"heading-medium\"}},{\"type\":\"table\",\"props\":{\"image_svg_color\":\"emphasis\",\"link_style\":\"default\",\"link_text\":\"Read more\",\"meta_style\":\"text-meta\",\"show_content\":true,\"show_image\":false,\"show_link\":false,\"show_meta\":false,\"show_title\":true,\"table_justify\":false,\"table_order\":\"1\",\"table_responsive\":\"overflow\",\"table_size\":\"small\",\"table_style\":\"striped\",\"table_width_meta\":\"shrink\",\"table_width_title\":\"shrink\"},\"children\":[{\"type\":\"table_item\",\"props\":{\"content\":\"\n\n<p>0 \\u2013 10 % &lt; 1,5% v.E. (Vom Endwert)(Feineinstellung)<\\\/p>\",\"meta\":\"\",\"title\":\"Genauigkeit im Teilbereich:\"}},{\"type\":\"table_item\",\"props\":{\"content\":\"\n\n<p>10 \\u2013 100 % &lt; 1,5% v.E. (Grobeinstellung)<\\\/p>\",\"meta\":\"\",\"title\":\"Genauigkeit im Teilbereich:\"}},{\"type\":\"table_item\",\"props\":{\"content\":\"\n\n<p>0,005 % v. E.<\\\/p>\",\"meta\":\"\",\"title\":\"Anzeigenaufl\\u00f6sung:\"}},{\"type\":\"table_item\",\"props\":{\"content\":\"\n\n<p>0,1 % v. M.\\\/\\u00b0C (v. M. = Vom Messwert)<\\\/p>\",\"meta\":\"\",\"title\":\"Temperatureinfluss auf den Messwert:\"}},{\"type\":\"table_item\",\"props\":{\"content\":\"\n\n<p>10 bar statisch<\\\/p>\",\"meta\":\"\",\"title\":\"Maximaler Betriebsdruck:\"}},{\"type\":\"table_item\",\"props\":{\"content\":\"\n\n<p>5.000 Nml \\\/ min<\\\/p>\",\"meta\":\"\",\"title\":\"Maximaler Durchfluss:\"}},{\"type\":\"table_item\",\"props\":{\"content\":\"\n\n<p>RS 232 (9-polig)<\\\/p>\",\"meta\":\"\",\"title\":\"Datenschnittstelle:\"}},{\"type\":\"table_item\",\"props\":{\"content\":\"\n\n<p>Leckkalibrator: 40 x 83 x 153 mm<br \\\/>Kunststoffkoffer: 82 x 275 x 230 mm<\\\/p>\",\"meta\":\"\",\"title\":\"Abmessungen (H x B x T):\"}},{\"type\":\"table_item\",\"props\":{\"content\":\"\n\n<p>Leckkalibrator: 0,4 kg<br \\\/>Kunststoffkoffer: 1,1 kg<\\\/p>\",\"meta\":\"\",\"title\":\"Gewicht:\"}},{\"type\":\"table_item\",\"props\":{\"content\":\"\n\n<p>2 x Batterien AA \\\/ 2 x 1,2 Volt NiMH-Akku \\\/ 3,3 Volt Weit bereichs-Steckernetzteil (100 \\u2013 240 VAC)<\\\/p>\",\"meta\":\"\",\"title\":\"Stromversorgung:\"}},{\"type\":\"table_item\",\"props\":{\"content\":\"\n\n<p>\\u00d6l- und wasserfreie Druckluft (ISO 8573-1 Klasse 3)<\\\/p>\",\"meta\":\"\",\"title\":\"Druckluftversorgung: \"}},{\"type\":\"table_item\",\"props\":{\"content\":\"\n\n<p>10 \\u00b0C \\u2013 40 \\u00b0C<\\\/p>\",\"meta\":\"\",\"title\":\"Temperaturmessbereich:\"}}]}]}]}],\"name\":\"Technische Daten\"},{\"type\":\"section\",\"props\":{\"image_position\":\"center-center\",\"style\":\"default\",\"title_breakpoint\":\"xl\",\"title_position\":\"top-left\",\"title_rotation\":\"left\",\"vertical_align\":\"\",\"width\":\"small\"},\"children\":[{\"type\":\"row\",\"children\":[{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"position_sticky_breakpoint\":\"m\",\"style\":\"tile-primary\",\"width_medium\":\"1-1\"},\"children\":[{\"type\":\"text\",\"props\":{\"column_breakpoint\":\"m\",\"content\":\"\n\n<p>Datenblatt Leckkalibrator<\\\/p>\",\"margin\":\"default\",\"margin_remove_bottom\":true,\"text_align\":\"center\"}},{\"type\":\"button\",\"props\":{\"grid_column_gap\":\"small\",\"grid_row_gap\":\"small\",\"margin\":\"default\",\"margin_remove_top\":true,\"text_align\":\"center\"},\"children\":[{\"type\":\"button_item\",\"props\":{\"button_style\":\"primary\",\"content\":\"Download (PDF)\",\"dialog_layout\":\"modal\",\"dialog_offcanvas_flip\":true,\"icon_align\":\"left\",\"link\":\"https:\\\/\\\/www.zeltwanger.de\\\/app\\\/uploads\\\/2025\\\/09\\\/rz_Datenblatt_Leckkalibrator_DE_2025_screen.pdf\",\"link_target\":\"blank\"}}]}]}]}],\"name\":\"Download Datenblatt Blaue Kachel\"},{\"type\":\"section\",\"props\":{\"image_position\":\"center-center\",\"padding_remove_bottom\":false,\"padding_remove_top\":true,\"style\":\"default\",\"title_breakpoint\":\"xl\",\"title_position\":\"top-left\",\"title_rotation\":\"left\",\"vertical_align\":\"\",\"width\":\"small\"},\"children\":[{\"type\":\"row\",\"props\":{\"width\":\"default\"},\"children\":[{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"position_sticky_breakpoint\":\"m\",\"width_medium\":\"1-1\"},\"children\":[{\"type\":\"headline\",\"props\":{\"content\":\"Verwandte Produkte\",\"text_align\":\"center\",\"title_color\":\"primary\",\"title_element\":\"h3\",\"title_style\":\"heading-medium\"}}]}]},{\"type\":\"row\",\"props\":{\"layout\":\"1-2,1-2\"},\"children\":[{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"position_sticky_breakpoint\":\"m\",\"width_medium\":\"1-2\"},\"children\":[{\"type\":\"image\",\"props\":{\"image\":\"app\\\/uploads\\\/2020\\\/03\\\/Zeltwanger_ZEDcore_002_DE_2019-09-23_web.png\",\"image_height\":\"337\",\"image_svg_color\":\"emphasis\",\"link\":\"de\\\/technologien\\\/dichtheitspruefung\\\/dichtheitspruefung-mit-luft\\\/zedcore\\\/\",\"margin\":\"default\",\"text_align\":\"center\"}},{\"type\":\"text\",\"props\":{\"column_breakpoint\":\"m\",\"content\":\"\n\n<p><a href=\\\"https:\\\/\\\/www.zeltwanger.de\\\/de\\\/technologien\\\/dichtheitspruefung\\\/dichtheitspruefung-mit-luft\\\/zedcore\\\/\\\">ZEDcore<\\\/a><\\\/p>\",\"margin\":\"default\",\"text_align\":\"center\"}}]},{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"position_sticky_breakpoint\":\"m\",\"width_medium\":\"1-2\"},\"children\":[{\"type\":\"image\",\"props\":{\"image\":\"app\\\/uploads\\\/2020\\\/02\\\/ZW_Website-2020_Pruefleck_420x337px_R01-1.png\",\"image_height\":\"285\",\"image_svg_color\":\"emphasis\",\"link\":\"de\\\/technologien\\\/dichtheitspruefung\\\/dichtheitspruefung-mit-luft\\\/pruefleck\\\/\",\"margin\":\"default\",\"text_align\":\"center\"}},{\"type\":\"text\",\"props\":{\"column_breakpoint\":\"m\",\"content\":\"\n\n<p><a href=\\\"https:\\\/\\\/www.zeltwanger.de\\\/de\\\/technologien\\\/dichtheitspruefung\\\/dichtheitspruefung-mit-luft\\\/pruefleck\\\/\\\">Pr\\u00fcfleck<\\\/a><\\\/p>\",\"margin\":\"default\",\"text_align\":\"center\"}}]}]}],\"name\":\"Weitere Produkte\"},{\"type\":\"section\",\"props\":{\"id\":\"flyout\",\"image_position\":\"center-center\",\"style\":\"default\",\"title_breakpoint\":\"xl\",\"title_position\":\"top-left\",\"title_rotation\":\"left\",\"vertical_align\":\"\",\"width\":\"default\"},\"children\":[{\"type\":\"row\",\"children\":[{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"position_sticky_breakpoint\":\"m\",\"width_medium\":\"1-1\"},\"children\":[{\"type\":\"flyout\",\"props\":{\"content_title\":\"Klingt interessant?\",\"flyout_button_text\":\"Kontaktieren Sie uns\",\"parent\":\"flyout\",\"show_content_title\":true,\"show_image\":true},\"children\":[{\"type\":\"flyout_item\",\"props\":{\"name_text\":\"20899\",\"post_id\":20899}},{\"type\":\"flyout_item\",\"props\":{\"name_text\":\"20900\",\"post_id\":20900}}]}]}]}],\"name\":\"Ansprechpartner Flyout\"}],\"version\":\"4.5.24\"} --><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Leckkalibrator F\u00fcr sichere Dichtheitspr\u00fcfger\u00e4te Unser Leckkalibrator dient zur \u00dcberpr\u00fcfung und Parametrierung von Lecktest- und Dichtheitspr\u00fcfger\u00e4ten. Hierf\u00fcr wird der Leckkalibrator an die Lecksimulation des Ger\u00e4tes angeschlossen und die gew\u00fcnschte Leckrate \u2013 in Abh\u00e4ngigkeit vom anstehenden Pr\u00fcfdruck \u2013 \u00fcber eine Pr\u00e4zisionsdrossel eingestellt. Lieferumfang 1 x ZELTWANGER Leckkalibrator 1 x Kunststoffkoffer mit Formeinsatz 1 x Netzteil 2 x [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":0,"parent":1790,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-5742","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Leckkalibrator | ZED-Zubeh\u00f6r | ZELTWANGER<\/title>\n<meta name=\"description\" content=\"Leckkalibrator zur \u00dcberpr\u00fcfung und Parametrierung von Lecktest- und Dichtheitspr\u00fcfger\u00e4ten | Zubeh\u00f6r f\u00fcr die ZED-Ger\u00e4tefamilie von ZELTWANGER\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.zeltwanger.de\/de\/technologien\/dichtheitspruefung\/dichtheitspruefung-mit-luft\/leckkalibrator\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Leckkalibrator | ZED-Zubeh\u00f6r | ZELTWANGER\" \/>\n<meta property=\"og:description\" content=\"Leckkalibrator zur \u00dcberpr\u00fcfung und Parametrierung von Lecktest- und Dichtheitspr\u00fcfger\u00e4ten | Zubeh\u00f6r f\u00fcr die ZED-Ger\u00e4tefamilie von ZELTWANGER\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.zeltwanger.de\/de\/technologien\/dichtheitspruefung\/dichtheitspruefung-mit-luft\/leckkalibrator\/\" \/>\n<meta property=\"og:site_name\" content=\"ZELTWANGER\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/zeltwanger.karriere\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-08T08:44:08+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.zeltwanger.de\\\/de\\\/technologien\\\/dichtheitspruefung\\\/dichtheitspruefung-mit-luft\\\/leckkalibrator\\\/\",\"url\":\"https:\\\/\\\/www.zeltwanger.de\\\/de\\\/technologien\\\/dichtheitspruefung\\\/dichtheitspruefung-mit-luft\\\/leckkalibrator\\\/\",\"name\":\"Leckkalibrator | ZED-Zubeh\u00f6r | ZELTWANGER\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.zeltwanger.de\\\/de\\\/#website\"},\"datePublished\":\"2020-02-28T13:05:36+00:00\",\"dateModified\":\"2025-09-08T08:44:08+00:00\",\"description\":\"Leckkalibrator zur \u00dcberpr\u00fcfung und Parametrierung von Lecktest- und Dichtheitspr\u00fcfger\u00e4ten | Zubeh\u00f6r f\u00fcr die ZED-Ger\u00e4tefamilie von ZELTWANGER\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.zeltwanger.de\\\/de\\\/technologien\\\/dichtheitspruefung\\\/dichtheitspruefung-mit-luft\\\/leckkalibrator\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.zeltwanger.de\\\/de\\\/technologien\\\/dichtheitspruefung\\\/dichtheitspruefung-mit-luft\\\/leckkalibrator\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.zeltwanger.de\\\/de\\\/technologien\\\/dichtheitspruefung\\\/dichtheitspruefung-mit-luft\\\/leckkalibrator\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.zeltwanger.de\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Technologien\",\"item\":\"https:\\\/\\\/www.zeltwanger.de\\\/de\\\/technologien\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"L\u00f6sungen f\u00fcr die Dichtheitspr\u00fcfung\",\"item\":\"https:\\\/\\\/www.zeltwanger.de\\\/de\\\/technologien\\\/dichtheitspruefung\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Dichtheitspr\u00fcfung mit Luft\",\"item\":\"https:\\\/\\\/www.zeltwanger.de\\\/de\\\/technologien\\\/dichtheitspruefung\\\/dichtheitspruefung-mit-luft\\\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"Leckkalibrator\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.zeltwanger.de\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.zeltwanger.de\\\/de\\\/\",\"name\":\"ZELTWANGER\",\"description\":\"Innovation aus Freude an Technik\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.zeltwanger.de\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.zeltwanger.de\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.zeltwanger.de\\\/de\\\/#organization\",\"name\":\"ZELTWANGER\",\"url\":\"https:\\\/\\\/www.zeltwanger.de\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.zeltwanger.de\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.zeltwanger.de\\\/app\\\/uploads\\\/2024\\\/03\\\/ZELTWANGER-Maennchen_nebeneinander_RGB_Screen_quadratisch_klein-e1710331495893.jpg\",\"contentUrl\":\"https:\\\/\\\/www.zeltwanger.de\\\/app\\\/uploads\\\/2024\\\/03\\\/ZELTWANGER-Maennchen_nebeneinander_RGB_Screen_quadratisch_klein-e1710331495893.jpg\",\"width\":144,\"height\":144,\"caption\":\"ZELTWANGER\"},\"image\":{\"@id\":\"https:\\\/\\\/www.zeltwanger.de\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/zeltwanger.karriere\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/11844117\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Leckkalibrator | ZED-Zubeh\u00f6r | ZELTWANGER","description":"Leckkalibrator zur \u00dcberpr\u00fcfung und Parametrierung von Lecktest- und Dichtheitspr\u00fcfger\u00e4ten | Zubeh\u00f6r f\u00fcr die ZED-Ger\u00e4tefamilie von ZELTWANGER","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.zeltwanger.de\/de\/technologien\/dichtheitspruefung\/dichtheitspruefung-mit-luft\/leckkalibrator\/","og_locale":"de_DE","og_type":"article","og_title":"Leckkalibrator | ZED-Zubeh\u00f6r | ZELTWANGER","og_description":"Leckkalibrator zur \u00dcberpr\u00fcfung und Parametrierung von Lecktest- und Dichtheitspr\u00fcfger\u00e4ten | Zubeh\u00f6r f\u00fcr die ZED-Ger\u00e4tefamilie von ZELTWANGER","og_url":"https:\/\/www.zeltwanger.de\/de\/technologien\/dichtheitspruefung\/dichtheitspruefung-mit-luft\/leckkalibrator\/","og_site_name":"ZELTWANGER","article_publisher":"https:\/\/www.facebook.com\/zeltwanger.karriere\/","article_modified_time":"2025-09-08T08:44:08+00:00","twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.zeltwanger.de\/de\/technologien\/dichtheitspruefung\/dichtheitspruefung-mit-luft\/leckkalibrator\/","url":"https:\/\/www.zeltwanger.de\/de\/technologien\/dichtheitspruefung\/dichtheitspruefung-mit-luft\/leckkalibrator\/","name":"Leckkalibrator | ZED-Zubeh\u00f6r | ZELTWANGER","isPartOf":{"@id":"https:\/\/www.zeltwanger.de\/de\/#website"},"datePublished":"2020-02-28T13:05:36+00:00","dateModified":"2025-09-08T08:44:08+00:00","description":"Leckkalibrator zur \u00dcberpr\u00fcfung und Parametrierung von Lecktest- und Dichtheitspr\u00fcfger\u00e4ten | Zubeh\u00f6r f\u00fcr die ZED-Ger\u00e4tefamilie von ZELTWANGER","breadcrumb":{"@id":"https:\/\/www.zeltwanger.de\/de\/technologien\/dichtheitspruefung\/dichtheitspruefung-mit-luft\/leckkalibrator\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.zeltwanger.de\/de\/technologien\/dichtheitspruefung\/dichtheitspruefung-mit-luft\/leckkalibrator\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.zeltwanger.de\/de\/technologien\/dichtheitspruefung\/dichtheitspruefung-mit-luft\/leckkalibrator\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.zeltwanger.de\/de\/"},{"@type":"ListItem","position":2,"name":"Technologien","item":"https:\/\/www.zeltwanger.de\/de\/technologien\/"},{"@type":"ListItem","position":3,"name":"L\u00f6sungen f\u00fcr die Dichtheitspr\u00fcfung","item":"https:\/\/www.zeltwanger.de\/de\/technologien\/dichtheitspruefung\/"},{"@type":"ListItem","position":4,"name":"Dichtheitspr\u00fcfung mit Luft","item":"https:\/\/www.zeltwanger.de\/de\/technologien\/dichtheitspruefung\/dichtheitspruefung-mit-luft\/"},{"@type":"ListItem","position":5,"name":"Leckkalibrator"}]},{"@type":"WebSite","@id":"https:\/\/www.zeltwanger.de\/de\/#website","url":"https:\/\/www.zeltwanger.de\/de\/","name":"ZELTWANGER","description":"Innovation aus Freude an Technik","publisher":{"@id":"https:\/\/www.zeltwanger.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.zeltwanger.de\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.zeltwanger.de\/de\/#organization","name":"ZELTWANGER","url":"https:\/\/www.zeltwanger.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.zeltwanger.de\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.zeltwanger.de\/app\/uploads\/2024\/03\/ZELTWANGER-Maennchen_nebeneinander_RGB_Screen_quadratisch_klein-e1710331495893.jpg","contentUrl":"https:\/\/www.zeltwanger.de\/app\/uploads\/2024\/03\/ZELTWANGER-Maennchen_nebeneinander_RGB_Screen_quadratisch_klein-e1710331495893.jpg","width":144,"height":144,"caption":"ZELTWANGER"},"image":{"@id":"https:\/\/www.zeltwanger.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/zeltwanger.karriere\/","https:\/\/www.linkedin.com\/company\/11844117\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.zeltwanger.de\/de\/wp-json\/wp\/v2\/pages\/5742","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.zeltwanger.de\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.zeltwanger.de\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.zeltwanger.de\/de\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.zeltwanger.de\/de\/wp-json\/wp\/v2\/comments?post=5742"}],"version-history":[{"count":67,"href":"https:\/\/www.zeltwanger.de\/de\/wp-json\/wp\/v2\/pages\/5742\/revisions"}],"predecessor-version":[{"id":34024,"href":"https:\/\/www.zeltwanger.de\/de\/wp-json\/wp\/v2\/pages\/5742\/revisions\/34024"}],"up":[{"embeddable":true,"href":"https:\/\/www.zeltwanger.de\/de\/wp-json\/wp\/v2\/pages\/1790"}],"wp:attachment":[{"href":"https:\/\/www.zeltwanger.de\/de\/wp-json\/wp\/v2\/media?parent=5742"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}