{"id":1790,"date":"2020-01-22T14:46:52","date_gmt":"2020-01-22T13:46:52","guid":{"rendered":"https:\/\/www.zeltwanger.de\/?page_id=1790"},"modified":"2025-06-16T15:15:21","modified_gmt":"2025-06-16T13:15:21","slug":"dichtheitspruefung-mit-luft","status":"publish","type":"page","link":"https:\/\/www.zeltwanger.de\/de\/technologien\/dichtheitspruefung\/dichtheitspruefung-mit-luft\/","title":{"rendered":"Dichtheitspr\u00fcfung mit Luft"},"content":{"rendered":"<h1>\n<p>Dichtheitspr\u00fcfung mit Luft<\/p>\n<\/h1>\n<h1>\n<p>Maximal flexibel <br \/>mit der ZED-Ger\u00e4tefamilie<\/p>\n<\/h1>\n<div>\n<p>Eine verl\u00e4ssliche Qualit\u00e4tssicherung hat immer Vorrang. Gleichzeitig gilt, dass sich Dichtheitspr\u00fcfung mit Luft leicht in Produktionsabl\u00e4ufe integrieren lassen muss, wenn sie wirtschaftlich sein soll.<\/p>\n<p>Daf\u00fcr sorgen wir mit den ZED Dichtheitspr\u00fcfger\u00e4ten.<\/p>\n<\/div>\n<div>\n<p>Ob kleines, mobiles Dichtheitspr\u00fcfger\u00e4t oder teilautomatisierte Pr\u00fcfstation \u2013 die ZED-Ger\u00e4tefamilie zeichnet sich durch maximale Flexibilit\u00e4t in der Dichtheitspr\u00fcfung mit Luft, aber auch mit anderen Nachweisgasen, aus.<\/p>\n<p>Die verschiedenen Ausf\u00fchrungen punkten durchweg mit ihrer leichten Bedienbarkeit, lassen sich problemlos in bestehende Prozesse implementieren und dank der eigenen Software-Entwicklung individuell an Kundenbed\u00fcrfnisse anpassen.<\/p>\n<\/div>\n<h2>Dichtheit flexibel messen im Plug-and-Play-Modus<\/h2>\n<div>\n<p>Mit dem modularen Messmodul <a href=\"https:\/\/www.zeltwanger.de\/de\/technologien\/dichtheitspruefung\/dichtheitspruefung-mit-luft\/zedcore\/\">ZEDcore<\/a>, das von Hand in die Ger\u00e4te eingesetzt und ausgetauscht werden kann, haben wir bei ZELTWANGER ein <strong>einzigartiges Baukastenprinzip<\/strong> entworfen.<\/p>\n<p>Dies erlaubt eine <strong>enge Vernetzung<\/strong> von Pr\u00fcfvorg\u00e4ngen mit unterschiedlichen Ger\u00e4ten an verschiedenen Punkten im Herstellungsprozess.<\/p>\n<\/p>\n<\/div>\n<p><a href=\"\/de\/technologien\/dichtheitspruefung\/dichtheitspruefung-mit-luft\/zedcore\/\"><img decoding=\"async\" src=\"\/app\/uploads\/2020\/04\/ZEDcore.png\" alt=\"Die modulare Messeinheit ZEDcore f\u00fcr flexible Dichtheitspr\u00fcfung mit Luft\"><\/a><\/p>\n<h3>\n<p>Die Vorteile des ZEDcore auf einen Blick:<\/p>\n<\/h3>\n<ul>\n<li>\n<div>\n<p>Es sind <strong>keine Programmierkenntnisse<\/strong> erforderlich, da das Messmodul im Plug-and-Play-Modus eingesetzt wird.<\/p>\n<\/div>\n<\/li>\n<li>\n<div>\n<p><strong>Verschiedene Messverfahren<\/strong> sind m\u00f6glich: Relativdruck, Relativdruck mit Glockenpr\u00fcfung, Relativdruck mit Durchfluss, Differenzdruck, Massefluss und Staudruck.<\/p>\n<\/div>\n<\/li>\n<li>\n<div>\n<p>Die <strong>Stillstandzeiten<\/strong> der Maschinen sind <strong>geringer<\/strong>, da die Installation der Dichtheitspr\u00fcfger\u00e4te wegf\u00e4llt.<\/p>\n<\/div>\n<\/li>\n<li>\n<div>\n<p>Es wird eine <strong>geringere Ersatzteilbevorratung<\/strong> ben\u00f6tigt, da die Messkreise einfach ausgetauscht werden k\u00f6nnen.<\/p>\n<\/div>\n<\/li>\n<li>\n<div>\n<p>Bei der Kalibrierung entsteht eine <strong>Zeit- und Kostenersparnis<\/strong>, da daf\u00fcr nur noch das Messmodul eingeschickt werden muss.<\/p>\n<\/div>\n<\/li>\n<li>\n<div>\n<p>Die Folgekosten sind geringer, denn es sind <strong>keine Stand-by-Ger\u00e4te<\/strong> mehr notwendig.<\/p>\n<\/div>\n<\/li>\n<\/ul>\n<p><p>\n        <a href=\"\/de\/technologien\/dichtheitspruefung\/dichtheitspruefung-mit-luft\/zedcore\/\">Das Plug-and-Play-Messmodul ZEDcore<\/a>\n    <\/p>\n<\/p>\n<h2>Dichtigkeitspr\u00fcfung mit Luft und weitere M\u00f6glichkeiten<\/h2>\n<div>\n<p>F\u00fcr eine schnelle und g\u00fcnstige Leckortung bietet sich sehr oft die Pr\u00fcfung mit Luft an. Seit Jahren sind wir bei ZELTWANGER<strong> Spezialisten auf den Gebieten der Druck\u00e4nderungsmessung sowie der Durchflussmessung<\/strong>. F\u00fcr die einzelnen Verfahren setzen wir dabei auf unsere ZED Dichtheitspr\u00fcfger\u00e4te.<\/p>\n<p>F\u00fcr eine Ortung von Kleinst-Leckagen haben wir au\u00dferdem <strong>hochpr\u00e4zise L\u00f6sungen zur Dichtheitspr\u00fcfung mit Helium und anderen Nachweisgasen<\/strong> entwickelt. Mit der ZED-Anlagenfamilie bieten wir hier standardisierte Anlagen mit drei verf\u00fcgbaren Pr\u00fcfverfahren.<\/p>\n<\/div>\n<p><p>\n        <a href=\"\/de\/technologien\/dichtheitspruefung\/dichtheitspruefung-mit-luft\/dichtheitspruefverfahren-mit-luft\/\">Pr\u00fcfverfahren mit Luft<\/a>\n    <\/p>\n<\/p>\n<p><p>\n        <a href=\"\/de\/technologien\/dichtheitspruefung\/dichtheitspruefung-mit-nachweisgasen\/\">Pr\u00fcfverfahren mit Nachweisgasen<\/a>\n    <\/p>\n<\/p>\n<p><p>\n        <a href=\"\/de\/produkte\/\">ZED Dichtheitspr\u00fcfger\u00e4te<\/a>\n    <\/p>\n<\/p>\n<p><img decoding=\"async\" src=\"\/app\/uploads\/2020\/04\/dichtheitspruefung_keyvisial.png\" alt=\"\"><\/p>\n<h2>\n<p>Flexibel und anpassbar \u2013 ZED Dichtheitspr\u00fcfger\u00e4te<\/p>\n<\/h2>\n<div>\n<p>Der Anspruch an unsere <strong>High-End-Dichtheitspr\u00fcfger\u00e4te<\/strong> ist eine schnellstm\u00f6gliche Anpassung an die Anforderungen, die Sie an die Pr\u00fcfvorg\u00e4nge haben.<\/p>\n<p>Neben den Lecktestger\u00e4ten geh\u00f6ren nicht nur das modulare Messmodul ZEDcore, sondern auch Steuer- und Auswerteeinheiten, eine Softwarel\u00f6sung, Adapter und weiteres Zubeh\u00f6r zur Kalibrierung dazu. So bieten wir mit der gesamten hochmodernen Ger\u00e4tefamilie f\u00fcr jede Umgebung die passenden M\u00f6glichkeiten.<\/p>\n<\/div>\n<h3>Die ZED Dichtheitspr\u00fcfger\u00e4te im \u00dcberblick<\/h3>\n<p><a href=\"\/de\/technologien\/dichtheitspruefung\/dichtheitspruefung-mit-luft\/zedcore\/\"><img decoding=\"async\" src=\"\/app\/uploads\/2020\/03\/Zeltwanger_ZEDcore_002_DE_2019-09-23_web.png\" alt=\"Das Messmodul ZEDcore zur Dichtheitspr\u00fcfung mit Luft\"><\/a><\/p>\n<p><p>\n        <a href=\"\/de\/technologien\/dichtheitspruefung\/dichtheitspruefung-mit-luft\/zedcore\/\">ZEDcore<\/a>\n    <\/p>\n<\/p>\n<div>\n<p>Das modulare Messmodul zur einfachen Integration in die ZED-Ger\u00e4tefamilie<\/p>\n<\/div>\n<p><a href=\"\/de\/technologien\/dichtheitspruefung\/dichtheitspruefung-mit-luft\/zedbase\/\"><img decoding=\"async\" src=\"\/app\/uploads\/2020\/04\/ZEDbase.png\" alt=\"Das Dichtheitspr\u00fcfger\u00e4t ZEDbase+ zur Dichtheitspr\u00fcfung mit Luft\"><\/a><\/p>\n<p><p>\n        <a href=\"\/de\/technologien\/dichtheitspruefung\/dichtheitspruefung-mit-luft\/zedbase\/\">ZEDbase+<\/a>\n    <\/p>\n<\/p>\n<div>\n<p>Flexibler Lecktester f\u00fcr Labore, Montagepl\u00e4tze oder Produktionslinien<\/p>\n<\/div>\n<p><a href=\"\/de\/technologien\/dichtheitspruefung\/dichtheitspruefung-mit-luft\/zedmod\/\"><img decoding=\"async\" src=\"\/app\/uploads\/2020\/04\/ZEDmod-1.png\" alt=\"Das Dichtheitspr\u00fcfger\u00e4t ZEDmod zur Dichtheitspr\u00fcfung mit Luft\"><\/a><\/p>\n<p><p>\n        <a href=\"\/de\/technologien\/dichtheitspruefung\/dichtheitspruefung-mit-luft\/zedmod\/\">ZEDmod<\/a>\n    <\/p>\n<\/p>\n<div>\n<p>Modulares Dichtheitspr\u00fcfger\u00e4t f\u00fcr komplexe Mehrkanalpr\u00fcfung mit bis zu acht Messkan\u00e4len<\/p>\n<\/div>\n<p><a href=\"\/de\/technologien\/dichtheitspruefung\/dichtheitspruefung-mit-luft\/zedsatellite\/\"><img decoding=\"async\" src=\"\/app\/uploads\/2020\/04\/ZEDsatellite.png\" alt=\"Das Dichtheitspr\u00fcfger\u00e4t ZEDsatellite zur Dichtheitspr\u00fcfung mit Luft\"><\/a><\/p>\n<p><p>\n        <a href=\"\/de\/technologien\/dichtheitspruefung\/dichtheitspruefung-mit-luft\/zedsatellite\/\">ZEDsatellite<\/a>\n    <\/p>\n<\/p>\n<div>\n<p>Das dezentrale Mess- und Pr\u00fcfmodul zur ortsnahen Integration in Anlagen<\/p>\n<\/div>\n<p><a href=\"\/de\/technologien\/dichtheitspruefung\/dichtheitspruefung-mit-luft\/zedeco\/\"><img decoding=\"async\" src=\"\/app\/uploads\/2023\/03\/ZEDeco-front_Schatten.png\" alt=\"Das Dichtheitspr\u00fcfger\u00e4t ZEDeco zur Dichtheitspr\u00fcfung mit Luft\"><\/a><\/p>\n<p><p>\n        <a href=\"\/de\/technologien\/dichtheitspruefung\/dichtheitspruefung-mit-luft\/zedeco\/\">ZEDeco+<\/a>\n    <\/p>\n<\/p>\n<div>\n<p>Industrie-4.0-f\u00e4higes Einkanal-Dichtheitspr\u00fcfger\u00e4t f\u00fcr Standardanwendungen<\/p>\n<\/div>\n<p><a href=\"\/de\/technologien\/dichtheitspruefung\/dichtheitspruefung-mit-luft\/zedbox\/\"><img decoding=\"async\" src=\"\/app\/uploads\/2020\/04\/ZEDbox.png\" alt=\"Die Steuereinheit ZEDbox zur Dichtheitspr\u00fcfung mit Luft\"><\/a><\/p>\n<p><p>\n        <a href=\"\/de\/technologien\/dichtheitspruefung\/dichtheitspruefung-mit-luft\/zedbox\/\">ZEDbox<\/a>\n    <\/p>\n<\/p>\n<div>\n<p>Die universelle Steuer- und Auswerteeinheit f\u00fcr dezentrale ZEDsatellite-Module<\/p>\n<\/div>\n<p><a href=\"\/de\/technologien\/dichtheitspruefung\/dichtheitspruefung-mit-luft\/zedflex\/\"><img decoding=\"async\" src=\"\/app\/uploads\/2020\/03\/Zeltwanger_ZEDflex_002_DE_2019-09-24_web.png\" alt=\"Das Dichtheitspr\u00fcfsystem ZEDflex zur Dichtheitspr\u00fcfung mit Luft\"><\/a><\/p>\n<p><p>\n        <a href=\"\/de\/technologien\/dichtheitspruefung\/dichtheitspruefung-mit-luft\/zedflex\/\">ZEDflex<\/a>\n    <\/p>\n<\/p>\n<div>\n<p>Flexibles Pr\u00fcfsystem mit bis zu acht Messmodulen, ZEDsatellite oder ZEDcore<\/p>\n<\/div>\n<p><a href=\"\/de\/technologien\/dichtheitspruefung\/dichtheitspruefung-mit-luft\/zedstation\/\"><img decoding=\"async\" src=\"\/app\/uploads\/2020\/03\/Zeltwanger_ZEDstation_002_DE_2019-09-20_web.png\" alt=\"Das Dichtheitspr\u00fcfger\u00e4t ZEDstation zur Dichtheitspr\u00fcfung mit Luft\"><\/a><\/p>\n<p><p>\n        <a href=\"\/de\/technologien\/dichtheitspruefung\/dichtheitspruefung-mit-luft\/zedstation\/\">ZEDstation<\/a>\n    <\/p>\n<\/p>\n<div>\n<p>Teilautomatisierte Pr\u00fcfstation mit kundenspezifischen Adaptionen<\/p>\n<\/div>\n<p><a href=\"\/de\/technologien\/dichtheitspruefung\/dichtheitspruefung-mit-luft\/zedsystem\/\"><img decoding=\"async\" src=\"\/app\/uploads\/2020\/04\/ZEDsystem.png\" alt=\"Das Dichtheitspr\u00fcfanlage ZEDsystem zur Dichtheitspr\u00fcfung mit Luft\"><\/a><\/p>\n<p><p>\n        <a href=\"\/de\/technologien\/dichtheitspruefung\/dichtheitspruefung-mit-luft\/zedsystem\/\">ZEDsystem<\/a>\n    <\/p>\n<\/p>\n<div>\n<p>Individuell konfigurierbare und automatisch beladbare Schiebeschlittenanlage<\/p>\n<\/div>\n<p><a href=\"\/de\/technologien\/dichtheitspruefung\/dichtheitspruefung-mit-luft\/zedflex\/#zedcontrol\"><img decoding=\"async\" src=\"\/app\/uploads\/2020\/03\/ZEDcontrol_front-1.png\" alt=\"Die Auswerteeinheit ZEDcontrol zur Dichtheitspr\u00fcfung mit Luft\"><\/a><\/p>\n<p><p>\n        <a href=\"\/de\/technologien\/dichtheitspruefung\/dichtheitspruefung-mit-luft\/zedflex\/#zedcontrol\">ZEDcontrol<\/a>\n    <\/p>\n<\/p>\n<div>\n<p>Die universelle 19\u201c-Steuer- und Auswerteeinheit der ZEDflex f\u00fcr bis zu acht Messmodule<\/p>\n<\/div>\n<p><a href=\"\/de\/technologien\/dichtheitspruefung\/dichtheitspruefung-mit-luft\/zedcon\/\"><img decoding=\"async\" src=\"\/app\/uploads\/2020\/02\/ZEDcon.png\" alt=\"Die Standardadapter ZEDcon zur Dichtheitspr\u00fcfung mit Luft\"><\/a><\/p>\n<p><p>\n        <a href=\"\/de\/technologien\/dichtheitspruefung\/dichtheitspruefung-mit-luft\/zedcon\/\">ZEDcon<\/a>\n    <\/p>\n<\/p>\n<div>\n<p>Die Standard-Adapterserie f\u00fcr die Verbindung der ZED-Ger\u00e4tefamilie mit dem Pr\u00fcfling<\/p>\n<\/div>\n<p><a href=\"\/de\/technologien\/dichtheitspruefung\/dichtheitspruefung-mit-luft\/zednet\/\"><img decoding=\"async\" src=\"\/app\/uploads\/2020\/03\/ZEDnet_SplashScreen.png\" alt=\"Die Softwarel\u00f6sung ZEDnet zur Dichtheitspr\u00fcfung mit Luft\"><\/a><\/p>\n<p><p>\n        <a href=\"\/de\/technologien\/dichtheitspruefung\/dichtheitspruefung-mit-luft\/zednet\/\">ZEDnet<\/a>\n    <\/p>\n<\/p>\n<div>\n<p>Die dezentrale Softwarel\u00f6sung f\u00fcr eine optimierte Verwaltung der ZED-Ger\u00e4te<\/p>\n<\/div>\n<p><a href=\"\/de\/technologien\/dichtheitspruefung\/dichtheitspruefung-mit-luft\/pruefleck\/\"><img decoding=\"async\" src=\"\/app\/uploads\/2020\/02\/ZW_Website-2020_Pruefleck_420x337px_R01-1.png\" alt=\"Festleck zur Dichtheitspr\u00fcfung mit Luft\"><\/a><\/p>\n<p><p>\n        <a href=\"\/de\/technologien\/dichtheitspruefung\/dichtheitspruefung-mit-luft\/pruefleck\/\">Zubeh\u00f6r: Pr\u00fcfleck<\/a>\n    <\/p>\n<\/p>\n<div>\n<p>Testleck zur \u00dcberpr\u00fcfung <br \/>und Parametrierung von Lecktest- und Dichtheitspr\u00fcfger\u00e4ten<\/p>\n<\/div>\n<p><a href=\"\/de\/technologien\/dichtheitspruefung\/dichtheitspruefung-mit-luft\/leckkalibrator\/\"><img decoding=\"async\" src=\"\/app\/uploads\/2020\/02\/ZW_Website-2020_Leckkalibrator_420x337px_R01-1.png\" alt=\"Leckkalibrator zur Dichtheitspr\u00fcfung mit Luft\"><\/a><\/p>\n<p><p>\n        <a href=\"\/de\/technologien\/dichtheitspruefung\/dichtheitspruefung-mit-luft\/leckkalibrator\/\">Zubeh\u00f6r: Leckkalibrator<\/a>\n    <\/p>\n<\/p>\n<div>\n<p>Variables Testleck zur \u00dcberpr\u00fcfung und Parametrierung von Lecktest- und Dichtheitspr\u00fcfger\u00e4ten<\/p>\n<\/div>\n<h2>Beratung gew\u00fcnscht?<\/h2>\n<div>\n<p>Wir verstehen uns in erster Linie als Fachinstanz, Berater und enger Partner unserer Kunden. Gemeinsam ermitteln wir deshalb mit Ihnen den Pr\u00fcfbedarf und die beste L\u00f6sung.<\/p>\n<\/div>\n<p><p>\n        <a href=\"\/de\/service\/dichtheitspruefung\/\">Kontaktieren Sie unseren Service<\/a>\n    <\/p>\n<\/p>\n<h3>Qualit\u00e4tssicherung ist unsere Kernkompetenz<\/h3>\n<h2>Das k\u00f6nnen wir<\/h2>\n<div>\n<p><a href=\"https:\/\/www.zeltwanger.de\/de\/unternehmen\/zeltwanger-dichtheitspruefung\/\">Mehr \u00fcber ZELTWANGER Dichtheitspr\u00fcfung<\/a><\/p>\n<\/div>\n<h2>Pr\u00fcfen mit Luft<\/h2>\n<div>\n<p>Durchfluss und Druck\u00e4nderung \u2013 f\u00fcr diese Verfahren sind wir Spezialisten<\/p>\n<\/div>\n<div>\n<p><a href=\"https:\/\/www.zeltwanger.de\/de\/technologien\/dichtheitspruefung\/dichtheitspruefung-mit-luft\/dichtheitspruefverfahren-mit-luft\/\">Dichtheitspr\u00fcfverfahren mit Luft<\/a><\/p>\n<\/div>\n<h2>Pr\u00fcfen mit Nachweisgasen<\/h2>\n<div>\n<p>Mit Helium und anderen Nachweisgasen kleinste Lecks finden<\/p>\n<\/div>\n<div>\n<p><a href=\"https:\/\/www.zeltwanger.de\/de\/technologien\/dichtheitspruefung\/dichtheitspruefung-mit-nachweisgasen\/\">Dichtheitspr\u00fcfung mit Nachweisgasen<\/a><\/p>\n<\/div>\n<div>\n<h1><\/h1>\n<p>Option: <\/p>\n<\/div>\n<p><!--more--><br \/>\n<!-- {\"type\":\"layout\",\"children\":[{\"type\":\"section\",\"props\":{\"class\":\"highlight-section\",\"image_position\":\"center-center\",\"padding\":\"xlarge\",\"style\":\"default\",\"title_breakpoint\":\"xl\",\"title_position\":\"top-left\",\"title_rotation\":\"left\",\"vertical_align\":\"\",\"width\":\"small\"},\"children\":[{\"type\":\"row\",\"props\":{\"width\":\"small\"},\"children\":[{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"position_sticky_breakpoint\":\"m\",\"text_color\":\"light\",\"width_medium\":\"1-1\"},\"children\":[{\"type\":\"headline\",\"props\":{\"content\":\"\n\n<p>Dichtheitspr\\u00fcfung mit Luft<\\\/p>\",\"text_align\":\"center\",\"title_element\":\"h1\",\"title_style\":\"heading-small\"}},{\"type\":\"headline\",\"props\":{\"content\":\"\n\n<p>Maximal flexibel <br \\\/>mit der ZED-Ger\\u00e4tefamilie<\\\/p>\",\"margin\":\"medium\",\"margin_remove_top\":true,\"text_align\":\"center\",\"title_element\":\"h1\",\"title_style\":\"heading-large\"}},{\"type\":\"text\",\"props\":{\"block_align\":\"center\",\"column_breakpoint\":\"m\",\"content\":\"\n\n<p>Eine verl\\u00e4ssliche Qualit\\u00e4tssicherung hat immer Vorrang. Gleichzeitig gilt, dass sich Dichtheitspr\\u00fcfung mit Luft leicht in Produktionsabl\\u00e4ufe integrieren lassen muss, wenn sie wirtschaftlich sein soll.<\\\/p>\\n\n\n<p>Daf\\u00fcr sorgen wir mit den ZED Dichtheitspr\\u00fcfger\\u00e4ten.<\\\/p>\",\"margin\":\"default\",\"maxwidth\":\"2xlarge\",\"text_align\":\"center\"}}]}]}],\"name\":\"Intro Text blauer Hintergrund\"},{\"type\":\"section\",\"props\":{\"class\":\"breadcrumb\",\"image_position\":\"center-center\",\"padding\":\"xsmall\",\"padding_remove_bottom\":true,\"padding_remove_top\":false,\"style\":\"default\",\"title_breakpoint\":\"xl\",\"title_position\":\"top-left\",\"title_rotation\":\"left\",\"vertical_align\":\"\",\"width\":\"default\"},\"children\":[{\"type\":\"row\",\"props\":{\"width\":\"small\"},\"children\":[{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"position_sticky_breakpoint\":\"m\",\"width_medium\":\"1-1\"},\"children\":[{\"type\":\"breadcrumbs\",\"props\":{\"image_svg_color\":\"emphasis\",\"margin\":\"default\"}}]}]}],\"name\":\"Breadcrumb\"},{\"type\":\"section\",\"props\":{\"image_position\":\"center-center\",\"padding_remove_bottom\":false,\"style\":\"default\",\"title_breakpoint\":\"xl\",\"title_position\":\"top-left\",\"title_rotation\":\"left\",\"vertical_align\":\"\",\"width\":\"small\"},\"children\":[{\"type\":\"row\",\"children\":[{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"position_sticky_breakpoint\":\"m\",\"width_medium\":\"1-1\"},\"children\":[{\"type\":\"text\",\"props\":{\"column_breakpoint\":\"m\",\"content\":\"\n\n<p>Ob kleines, mobiles Dichtheitspr\\u00fcfger\\u00e4t oder teilautomatisierte Pr\\u00fcfstation \\u2013 die ZED-Ger\\u00e4tefamilie zeichnet sich durch maximale Flexibilit\\u00e4t in der Dichtheitspr\\u00fcfung mit Luft, aber auch mit anderen Nachweisgasen, aus.<\\\/p>\\n\n\n<p>Die verschiedenen Ausf\\u00fchrungen punkten durchweg mit ihrer leichten Bedienbarkeit, lassen sich problemlos in bestehende Prozesse implementieren und dank der eigenen Software-Entwicklung individuell an Kundenbed\\u00fcrfnisse anpassen.<\\\/p>\",\"margin\":\"default\",\"text_align\":\"center\"}}]}]}],\"name\":\"Intro Text\"},{\"type\":\"section\",\"props\":{\"image_position\":\"center-center\",\"padding_remove_bottom\":false,\"style\":\"secondary\",\"title_breakpoint\":\"xl\",\"title_position\":\"top-left\",\"title_rotation\":\"left\",\"vertical_align\":\"\",\"width\":\"small\"},\"children\":[{\"type\":\"row\",\"children\":[{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"position_sticky_breakpoint\":\"m\",\"width_medium\":\"1-1\"},\"children\":[{\"type\":\"headline\",\"props\":{\"content\":\"Dichtheit flexibel messen im Plug-and-Play-Modus\",\"title_element\":\"h2\",\"title_style\":\"heading-medium\"}},{\"type\":\"text\",\"props\":{\"column_breakpoint\":\"m\",\"content\":\"\n\n<p>Mit dem modularen Messmodul <a href=\\\"https:\\\/\\\/www.zeltwanger.de\\\/de\\\/technologien\\\/dichtheitspruefung\\\/dichtheitspruefung-mit-luft\\\/zedcore\\\/\\\">ZEDcore<\\\/a>, das von Hand in die Ger\\u00e4te eingesetzt und ausgetauscht werden kann, haben wir bei ZELTWANGER ein <strong>einzigartiges Baukastenprinzip<\\\/strong> entworfen.<\\\/p>\\n\n\n<p>Dies erlaubt eine <strong>enge Vernetzung<\\\/strong> von Pr\\u00fcfvorg\\u00e4ngen mit unterschiedlichen Ger\\u00e4ten an verschiedenen Punkten im Herstellungsprozess.<\\\/p>\\n\n\n<p><\\\/p>\",\"margin\":\"default\"}},{\"type\":\"image\",\"props\":{\"image\":\"app\\\/uploads\\\/2020\\\/04\\\/ZEDcore.png\",\"image_alt\":\"Die modulare Messeinheit ZEDcore f\\u00fcr flexible Dichtheitspr\\u00fcfung mit Luft\",\"image_svg_color\":\"emphasis\",\"link\":\"de\\\/technologien\\\/dichtheitspruefung\\\/dichtheitspruefung-mit-luft\\\/zedcore\\\/\",\"margin\":\"default\",\"margin_remove_bottom\":false,\"margin_remove_top\":false,\"text_align\":\"center\"}},{\"type\":\"headline\",\"props\":{\"content\":\"\n\n<p>Die Vorteile des ZEDcore auf einen Blick:<\\\/p>\",\"title_element\":\"h3\",\"title_style\":\"h4\"}},{\"type\":\"list\",\"props\":{\"column_breakpoint\":\"m\",\"icon\":\"plus\",\"icon_width\":16,\"image_align\":\"left\",\"image_svg_color\":\"emphasis\",\"image_vertical_align\":false,\"list_element\":\"ul\",\"list_horizontal_separator\":\", \",\"list_type\":\"vertical\",\"show_image\":true,\"show_link\":true},\"children\":[{\"type\":\"list_item\",\"props\":{\"content\":\"\n\n<p>Es sind <strong>keine Programmierkenntnisse<\\\/strong> erforderlich, da das Messmodul im Plug-and-Play-Modus eingesetzt wird.<\\\/p>\",\"icon\":\"plus\"}},{\"type\":\"list_item\",\"props\":{\"content\":\"\n\n<p><strong>Verschiedene Messverfahren<\\\/strong> sind m\\u00f6glich: Relativdruck, Relativdruck mit Glockenpr\\u00fcfung, Relativdruck mit Durchfluss, Differenzdruck, Massefluss und Staudruck.<\\\/p>\"}},{\"type\":\"list_item\",\"props\":{\"content\":\"\n\n<p>Die <strong>Stillstandzeiten<\\\/strong> der Maschinen sind <strong>geringer<\\\/strong>, da die Installation der Dichtheitspr\\u00fcfger\\u00e4te wegf\\u00e4llt.<\\\/p>\"}},{\"type\":\"list_item\",\"props\":{\"content\":\"\n\n<p>Es wird eine <strong>geringere Ersatzteilbevorratung<\\\/strong> ben\\u00f6tigt, da die Messkreise einfach ausgetauscht werden k\\u00f6nnen.<\\\/p>\"}},{\"type\":\"list_item\",\"props\":{\"content\":\"\n\n<p>Bei der Kalibrierung entsteht eine <strong>Zeit- und Kostenersparnis<\\\/strong>, da daf\\u00fcr nur noch das Messmodul eingeschickt werden muss.<\\\/p>\"}},{\"type\":\"list_item\",\"props\":{\"content\":\"\n\n<p>Die Folgekosten sind geringer, denn es sind <strong>keine Stand-by-Ger\\u00e4te<\\\/strong> mehr notwendig.<\\\/p>\"}}]},{\"type\":\"button\",\"props\":{\"grid_column_gap\":\"small\",\"grid_row_gap\":\"small\",\"margin\":\"medium\",\"text_align\":\"center\"},\"children\":[{\"type\":\"button_item\",\"props\":{\"button_style\":\"default\",\"content\":\"Das Plug-and-Play-Messmodul ZEDcore\",\"dialog_layout\":\"modal\",\"dialog_offcanvas_flip\":true,\"icon_align\":\"left\",\"link\":\"de\\\/technologien\\\/dichtheitspruefung\\\/dichtheitspruefung-mit-luft\\\/zedcore\\\/\",\"link_title\":\"Link zur Produktseite ZEDcore\"}}]}]}]}],\"name\":\"Plug and Play\"},{\"type\":\"section\",\"props\":{\"image_position\":\"center-center\",\"padding_remove_bottom\":false,\"style\":\"default\",\"title_breakpoint\":\"xl\",\"title_position\":\"top-left\",\"title_rotation\":\"left\",\"vertical_align\":\"\",\"width\":\"small\"},\"children\":[{\"type\":\"row\",\"props\":{\"layout\":\"2-3,1-3\"},\"children\":[{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"position_sticky_breakpoint\":\"m\",\"width_medium\":\"2-3\"},\"children\":[{\"type\":\"headline\",\"props\":{\"content\":\"Dichtigkeitspr\\u00fcfung mit Luft und weitere M\\u00f6glichkeiten\",\"margin_remove_bottom\":true,\"title_element\":\"h2\"}},{\"type\":\"text\",\"props\":{\"column_breakpoint\":\"m\",\"content\":\"\n\n<p>F\\u00fcr eine schnelle und g\\u00fcnstige Leckortung bietet sich sehr oft die Pr\\u00fcfung mit Luft an. Seit Jahren sind wir bei ZELTWANGER<strong> Spezialisten auf den Gebieten der Druck\\u00e4nderungsmessung sowie der Durchflussmessung<\\\/strong>. F\\u00fcr die einzelnen Verfahren setzen wir dabei auf unsere ZED Dichtheitspr\\u00fcfger\\u00e4te.<\\\/p>\\n\n\n<p>F\\u00fcr eine Ortung von Kleinst-Leckagen haben wir au\\u00dferdem <strong>hochpr\\u00e4zise L\\u00f6sungen zur Dichtheitspr\\u00fcfung mit Helium und anderen Nachweisgasen<\\\/strong> entwickelt. Mit der ZED-Anlagenfamilie bieten wir hier standardisierte Anlagen mit drei verf\\u00fcgbaren Pr\\u00fcfverfahren.<\\\/p>\",\"margin\":\"default\"}},{\"type\":\"button\",\"props\":{\"grid_column_gap\":\"small\",\"grid_row_gap\":\"small\",\"margin\":\"medium\",\"text_align\":\"left\"},\"children\":[{\"type\":\"button_item\",\"props\":{\"button_style\":\"default\",\"content\":\"Pr\\u00fcfverfahren mit Luft\",\"dialog_layout\":\"modal\",\"dialog_offcanvas_flip\":true,\"icon_align\":\"left\",\"link\":\"de\\\/technologien\\\/dichtheitspruefung\\\/dichtheitspruefung-mit-luft\\\/dichtheitspruefverfahren-mit-luft\\\/\",\"link_title\":\"Link zur Technologieseite Pr\\u00fcfverfahren mit Luft\"}}]},{\"type\":\"button\",\"props\":{\"grid_column_gap\":\"small\",\"grid_row_gap\":\"small\",\"margin\":\"medium\",\"text_align\":\"left\"},\"children\":[{\"type\":\"button_item\",\"props\":{\"button_style\":\"default\",\"content\":\"Pr\\u00fcfverfahren mit Nachweisgasen\",\"dialog_layout\":\"modal\",\"dialog_offcanvas_flip\":true,\"icon_align\":\"left\",\"link\":\"de\\\/technologien\\\/dichtheitspruefung\\\/dichtheitspruefung-mit-nachweisgasen\\\/\",\"link_title\":\"Link zur Technologieseite Pr\\u00fcfverfahren mit Nachweisgasen\"}}]},{\"type\":\"button\",\"props\":{\"grid_column_gap\":\"small\",\"grid_row_gap\":\"small\",\"margin\":\"medium\",\"text_align\":\"left\"},\"children\":[{\"type\":\"button_item\",\"props\":{\"button_style\":\"default\",\"content\":\"ZED Dichtheitspr\\u00fcfger\\u00e4te\",\"dialog_layout\":\"modal\",\"dialog_offcanvas_flip\":true,\"icon_align\":\"left\",\"link\":\"de\\\/produkte\\\/\",\"link_title\":\"Link zur ZED Dichtheitspr\\u00fcfger\\u00e4te\"}}]}]},{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"position_sticky_breakpoint\":\"m\",\"width_medium\":\"1-3\"},\"children\":[{\"type\":\"image\",\"props\":{\"image\":\"app\\\/uploads\\\/2020\\\/04\\\/dichtheitspruefung_keyvisial.png\",\"image_svg_color\":\"emphasis\",\"margin\":\"default\"}}]}]}],\"name\":\"Pr\\u00fcfverfahren\"},{\"type\":\"section\",\"props\":{\"image_position\":\"center-center\",\"padding_remove_bottom\":false,\"padding_remove_top\":false,\"style\":\"secondary\",\"title_breakpoint\":\"xl\",\"title_position\":\"top-left\",\"title_rotation\":\"left\",\"vertical_align\":\"\",\"width\":\"small\"},\"children\":[{\"type\":\"row\",\"children\":[{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"position_sticky_breakpoint\":\"m\",\"width_medium\":\"1-1\"},\"children\":[{\"type\":\"headline\",\"props\":{\"content\":\"\n\n<p>Flexibel und anpassbar \\u2013 ZED Dichtheitspr\\u00fcfger\\u00e4te<\\\/p>\",\"title_element\":\"h2\"}},{\"type\":\"text\",\"props\":{\"column_breakpoint\":\"m\",\"content\":\"\n\n<p>Der Anspruch an unsere <strong>High-End-Dichtheitspr\\u00fcfger\\u00e4te<\\\/strong> ist eine schnellstm\\u00f6gliche Anpassung an die Anforderungen, die Sie an die Pr\\u00fcfvorg\\u00e4nge haben.<\\\/p>\\n\n\n<p>Neben den Lecktestger\\u00e4ten geh\\u00f6ren nicht nur das modulare Messmodul ZEDcore, sondern auch Steuer- und Auswerteeinheiten, eine Softwarel\\u00f6sung, Adapter und weiteres Zubeh\\u00f6r zur Kalibrierung dazu. So bieten wir mit der gesamten hochmodernen Ger\\u00e4tefamilie f\\u00fcr jede Umgebung die passenden M\\u00f6glichkeiten.<\\\/p>\",\"margin\":\"default\"}}]}]},{\"type\":\"row\",\"props\":{\"margin\":\"medium\"},\"children\":[{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"position_sticky_breakpoint\":\"m\",\"width_medium\":\"1-1\"},\"children\":[{\"type\":\"headline\",\"props\":{\"content\":\"Die ZED Dichtheitspr\\u00fcfger\\u00e4te im \\u00dcberblick\",\"title_element\":\"h3\"}}]}]},{\"type\":\"row\",\"props\":{\"layout\":\"1-3,1-3,1-3\",\"margin\":\"large\",\"margin_remove_top\":true},\"children\":[{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"position_sticky_breakpoint\":\"m\",\"vertical_align\":\"bottom\",\"width_small\":\"1-3\"},\"children\":[{\"type\":\"image\",\"props\":{\"image\":\"app\\\/uploads\\\/2020\\\/03\\\/Zeltwanger_ZEDcore_002_DE_2019-09-23_web.png\",\"image_alt\":\"Das Messmodul ZEDcore zur Dichtheitspr\\u00fcfung mit Luft\",\"image_svg_color\":\"emphasis\",\"image_width\":\"275\",\"link\":\"de\\\/technologien\\\/dichtheitspruefung\\\/dichtheitspruefung-mit-luft\\\/zedcore\\\/\",\"margin\":\"default\",\"text_align\":\"center\"}},{\"type\":\"button\",\"props\":{\"grid_column_gap\":\"small\",\"grid_row_gap\":\"small\",\"margin\":\"\",\"text_align\":\"center\"},\"children\":[{\"type\":\"button_item\",\"props\":{\"button_style\":\"\",\"content\":\"ZEDcore\",\"dialog_layout\":\"modal\",\"dialog_offcanvas_flip\":true,\"icon_align\":\"left\",\"link\":\"de\\\/technologien\\\/dichtheitspruefung\\\/dichtheitspruefung-mit-luft\\\/zedcore\\\/\",\"link_title\":\"Link zur Produktseite ZEDcore\"}}]},{\"type\":\"text\",\"props\":{\"column_breakpoint\":\"m\",\"content\":\"\n\n<p>Das modulare Messmodul zur einfachen Integration in die ZED-Ger\\u00e4tefamilie<\\\/p>\",\"margin\":\"default\",\"margin_remove_top\":false,\"text_align\":\"center\"}}]},{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"position_sticky_breakpoint\":\"m\",\"vertical_align\":\"bottom\",\"width_small\":\"1-3\"},\"children\":[{\"type\":\"image\",\"props\":{\"image\":\"app\\\/uploads\\\/2020\\\/04\\\/ZEDbase.png\",\"image_alt\":\"Das Dichtheitspr\\u00fcfger\\u00e4t ZEDbase+ zur Dichtheitspr\\u00fcfung mit Luft\",\"image_svg_color\":\"emphasis\",\"link\":\"de\\\/technologien\\\/dichtheitspruefung\\\/dichtheitspruefung-mit-luft\\\/zedbase\\\/\",\"margin\":\"default\",\"text_align\":\"center\"}},{\"type\":\"button\",\"props\":{\"grid_column_gap\":\"small\",\"grid_row_gap\":\"small\",\"margin\":\"\",\"text_align\":\"center\"},\"children\":[{\"type\":\"button_item\",\"props\":{\"button_style\":\"\",\"content\":\"ZEDbase+\",\"dialog_layout\":\"modal\",\"dialog_offcanvas_flip\":true,\"icon_align\":\"left\",\"link\":\"de\\\/technologien\\\/dichtheitspruefung\\\/dichtheitspruefung-mit-luft\\\/zedbase\\\/\",\"link_title\":\"Link zur Produktseite ZEDbase+\"}}]},{\"type\":\"text\",\"props\":{\"column_breakpoint\":\"m\",\"content\":\"\n\n<p>Flexibler Lecktester f\\u00fcr Labore, Montagepl\\u00e4tze oder Produktionslinien<\\\/p>\",\"margin\":\"default\",\"text_align\":\"center\"}}]},{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"position_sticky_breakpoint\":\"m\",\"vertical_align\":\"bottom\",\"width_small\":\"1-3\"},\"children\":[{\"type\":\"image\",\"props\":{\"image\":\"app\\\/uploads\\\/2020\\\/04\\\/ZEDmod-1.png\",\"image_alt\":\"Das Dichtheitspr\\u00fcfger\\u00e4t ZEDmod zur Dichtheitspr\\u00fcfung mit Luft\",\"image_svg_color\":\"emphasis\",\"link\":\"de\\\/technologien\\\/dichtheitspruefung\\\/dichtheitspruefung-mit-luft\\\/zedmod\\\/\",\"margin\":\"default\",\"position\":\"relative\",\"position_bottom\":\"-5\",\"text_align\":\"center\"}},{\"type\":\"button\",\"props\":{\"grid_column_gap\":\"small\",\"grid_row_gap\":\"small\",\"margin\":\"\",\"text_align\":\"center\"},\"children\":[{\"type\":\"button_item\",\"props\":{\"button_style\":\"\",\"content\":\"ZEDmod\",\"dialog_layout\":\"modal\",\"dialog_offcanvas_flip\":true,\"icon_align\":\"left\",\"link\":\"de\\\/technologien\\\/dichtheitspruefung\\\/dichtheitspruefung-mit-luft\\\/zedmod\\\/\",\"link_title\":\"Link zur Produktseite ZEDmod\"}}]},{\"type\":\"text\",\"props\":{\"column_breakpoint\":\"m\",\"content\":\"\n\n<p>Modulares Dichtheitspr\\u00fcfger\\u00e4t f\\u00fcr komplexe Mehrkanalpr\\u00fcfung mit bis zu acht Messkan\\u00e4len<\\\/p>\",\"margin\":\"default\",\"text_align\":\"center\"}}]}]},{\"type\":\"row\",\"props\":{\"layout\":\"1-3,1-3,1-3\",\"margin\":\"large\"},\"children\":[{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"position_sticky_breakpoint\":\"m\",\"vertical_align\":\"bottom\",\"width_small\":\"1-3\"},\"children\":[{\"type\":\"image\",\"props\":{\"image\":\"app\\\/uploads\\\/2020\\\/04\\\/ZEDsatellite.png\",\"image_alt\":\"Das Dichtheitspr\\u00fcfger\\u00e4t ZEDsatellite zur Dichtheitspr\\u00fcfung mit Luft\",\"image_svg_color\":\"emphasis\",\"link\":\"de\\\/technologien\\\/dichtheitspruefung\\\/dichtheitspruefung-mit-luft\\\/zedsatellite\\\/\",\"margin\":\"default\",\"text_align\":\"center\"}},{\"type\":\"button\",\"props\":{\"grid_column_gap\":\"small\",\"grid_row_gap\":\"small\",\"margin\":\"\",\"text_align\":\"center\"},\"children\":[{\"type\":\"button_item\",\"props\":{\"button_style\":\"\",\"content\":\"ZEDsatellite\",\"dialog_layout\":\"modal\",\"dialog_offcanvas_flip\":true,\"icon_align\":\"left\",\"link\":\"de\\\/technologien\\\/dichtheitspruefung\\\/dichtheitspruefung-mit-luft\\\/zedsatellite\\\/\",\"link_title\":\"Link zur Produktseite ZEDsatellite\"}}]},{\"type\":\"text\",\"props\":{\"column_breakpoint\":\"m\",\"content\":\"\n\n<p>Das dezentrale Mess- und Pr\\u00fcfmodul zur ortsnahen Integration in Anlagen<\\\/p>\",\"margin\":\"default\",\"text_align\":\"center\"}}]},{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"position_sticky_breakpoint\":\"m\",\"vertical_align\":\"bottom\",\"width_small\":\"1-3\"},\"children\":[{\"type\":\"image\",\"props\":{\"image\":\"app\\\/uploads\\\/2023\\\/03\\\/ZEDeco-front_Schatten.png\",\"image_alt\":\"Das Dichtheitspr\\u00fcfger\\u00e4t ZEDeco zur Dichtheitspr\\u00fcfung mit Luft\",\"image_svg_color\":\"emphasis\",\"image_width\":\"200\",\"link\":\"de\\\/technologien\\\/dichtheitspruefung\\\/dichtheitspruefung-mit-luft\\\/zedeco\\\/\",\"margin\":\"default\",\"position\":\"relative\",\"position_bottom\":\"-7\",\"position_left\":\"0\",\"text_align\":\"center\"}},{\"type\":\"button\",\"props\":{\"grid_column_gap\":\"small\",\"grid_row_gap\":\"small\",\"margin\":\"\",\"text_align\":\"center\"},\"children\":[{\"type\":\"button_item\",\"props\":{\"button_style\":\"\",\"content\":\"ZEDeco+\",\"dialog_layout\":\"modal\",\"dialog_offcanvas_flip\":true,\"icon_align\":\"left\",\"link\":\"de\\\/technologien\\\/dichtheitspruefung\\\/dichtheitspruefung-mit-luft\\\/zedeco\\\/\",\"link_title\":\"Link zur Produktseite ZEDeco\"}}]},{\"type\":\"text\",\"props\":{\"column_breakpoint\":\"m\",\"content\":\"\n\n<p>Industrie-4.0-f\\u00e4higes Einkanal-Dichtheitspr\\u00fcfger\\u00e4t f\\u00fcr Standardanwendungen<\\\/p>\",\"margin\":\"default\",\"text_align\":\"center\"}}]},{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"position_sticky_breakpoint\":\"m\",\"vertical_align\":\"bottom\",\"width_small\":\"1-3\"},\"children\":[{\"type\":\"image\",\"props\":{\"image\":\"app\\\/uploads\\\/2020\\\/04\\\/ZEDbox.png\",\"image_alt\":\"Die Steuereinheit ZEDbox zur Dichtheitspr\\u00fcfung mit Luft\",\"image_svg_color\":\"emphasis\",\"link\":\"de\\\/technologien\\\/dichtheitspruefung\\\/dichtheitspruefung-mit-luft\\\/zedbox\\\/\",\"margin\":\"default\",\"text_align\":\"center\"}},{\"type\":\"button\",\"props\":{\"grid_column_gap\":\"small\",\"grid_row_gap\":\"small\",\"margin\":\"\",\"text_align\":\"center\"},\"children\":[{\"type\":\"button_item\",\"props\":{\"button_style\":\"\",\"content\":\"ZEDbox\",\"dialog_layout\":\"modal\",\"dialog_offcanvas_flip\":true,\"icon_align\":\"left\",\"link\":\"de\\\/technologien\\\/dichtheitspruefung\\\/dichtheitspruefung-mit-luft\\\/zedbox\\\/\",\"link_title\":\"Link zur Produktseite ZEDbox\"}}]},{\"type\":\"text\",\"props\":{\"column_breakpoint\":\"m\",\"content\":\"\n\n<p>Die universelle Steuer- und Auswerteeinheit f\\u00fcr dezentrale ZEDsatellite-Module<\\\/p>\",\"margin\":\"default\",\"text_align\":\"center\"}}]}]},{\"type\":\"row\",\"props\":{\"layout\":\"1-3,1-3,1-3\"},\"children\":[{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"position_sticky_breakpoint\":\"m\",\"vertical_align\":\"bottom\",\"width_small\":\"1-3\"},\"children\":[{\"type\":\"image\",\"props\":{\"image\":\"app\\\/uploads\\\/2020\\\/03\\\/Zeltwanger_ZEDflex_002_DE_2019-09-24_web.png\",\"image_alt\":\"Das Dichtheitspr\\u00fcfsystem ZEDflex zur Dichtheitspr\\u00fcfung mit Luft\",\"image_svg_color\":\"emphasis\",\"image_width\":\"230\",\"link\":\"de\\\/technologien\\\/dichtheitspruefung\\\/dichtheitspruefung-mit-luft\\\/zedflex\\\/\",\"margin\":\"default\",\"position\":\"relative\",\"position_bottom\":\"-10\",\"text_align\":\"center\"}},{\"type\":\"button\",\"props\":{\"grid_column_gap\":\"small\",\"grid_row_gap\":\"small\",\"margin\":\"\",\"text_align\":\"center\"},\"children\":[{\"type\":\"button_item\",\"props\":{\"button_style\":\"\",\"content\":\"ZEDflex\",\"dialog_layout\":\"modal\",\"dialog_offcanvas_flip\":true,\"icon_align\":\"left\",\"link\":\"de\\\/technologien\\\/dichtheitspruefung\\\/dichtheitspruefung-mit-luft\\\/zedflex\\\/\",\"link_title\":\"Link zur Produktseite ZEDflex\"}}]},{\"type\":\"text\",\"props\":{\"column_breakpoint\":\"m\",\"content\":\"\n\n<p>Flexibles Pr\\u00fcfsystem mit bis zu acht Messmodulen, ZEDsatellite oder ZEDcore<\\\/p>\",\"margin\":\"default\",\"text_align\":\"center\"}}]},{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"position_sticky_breakpoint\":\"m\",\"vertical_align\":\"bottom\",\"width_small\":\"1-3\"},\"children\":[{\"type\":\"image\",\"props\":{\"image\":\"app\\\/uploads\\\/2020\\\/03\\\/Zeltwanger_ZEDstation_002_DE_2019-09-20_web.png\",\"image_alt\":\"Das Dichtheitspr\\u00fcfger\\u00e4t ZEDstation zur Dichtheitspr\\u00fcfung mit Luft\",\"image_svg_color\":\"emphasis\",\"image_width\":\"250\",\"link\":\"de\\\/technologien\\\/dichtheitspruefung\\\/dichtheitspruefung-mit-luft\\\/zedstation\\\/\",\"margin\":\"default\",\"text_align\":\"center\"}},{\"type\":\"button\",\"props\":{\"grid_column_gap\":\"small\",\"grid_row_gap\":\"small\",\"margin\":\"\",\"text_align\":\"center\"},\"children\":[{\"type\":\"button_item\",\"props\":{\"button_style\":\"\",\"content\":\"ZEDstation\",\"dialog_layout\":\"modal\",\"dialog_offcanvas_flip\":true,\"icon_align\":\"left\",\"link\":\"de\\\/technologien\\\/dichtheitspruefung\\\/dichtheitspruefung-mit-luft\\\/zedstation\\\/\",\"link_title\":\"Link zur Produktseite ZEDstation\"}}]},{\"type\":\"text\",\"props\":{\"column_breakpoint\":\"m\",\"content\":\"\n\n<p>Teilautomatisierte Pr\\u00fcfstation mit kundenspezifischen Adaptionen<\\\/p>\",\"margin\":\"default\",\"text_align\":\"center\"}}]},{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"position_sticky_breakpoint\":\"m\",\"vertical_align\":\"bottom\",\"width_small\":\"1-3\"},\"children\":[{\"type\":\"image\",\"props\":{\"image\":\"app\\\/uploads\\\/2020\\\/04\\\/ZEDsystem.png\",\"image_alt\":\"Das Dichtheitspr\\u00fcfanlage ZEDsystem zur Dichtheitspr\\u00fcfung mit Luft\",\"image_svg_color\":\"emphasis\",\"link\":\"de\\\/technologien\\\/dichtheitspruefung\\\/dichtheitspruefung-mit-luft\\\/zedsystem\\\/\",\"margin\":\"default\",\"text_align\":\"center\"}},{\"type\":\"button\",\"props\":{\"grid_column_gap\":\"small\",\"grid_row_gap\":\"small\",\"margin\":\"\",\"text_align\":\"center\"},\"children\":[{\"type\":\"button_item\",\"props\":{\"button_style\":\"\",\"content\":\"ZEDsystem\",\"dialog_layout\":\"modal\",\"dialog_offcanvas_flip\":true,\"icon_align\":\"left\",\"link\":\"de\\\/technologien\\\/dichtheitspruefung\\\/dichtheitspruefung-mit-luft\\\/zedsystem\\\/\",\"link_title\":\"Link zur Produktseite ZEDsystem\"}}]},{\"type\":\"text\",\"props\":{\"column_breakpoint\":\"m\",\"content\":\"\n\n<p>Individuell konfigurierbare und automatisch beladbare Schiebeschlittenanlage<\\\/p>\",\"margin\":\"default\",\"text_align\":\"center\"}}]}]},{\"type\":\"row\",\"props\":{\"layout\":\"1-3,1-3,1-3\",\"margin\":\"large\"},\"children\":[{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"position_sticky_breakpoint\":\"m\",\"vertical_align\":\"bottom\",\"width_small\":\"1-3\"},\"children\":[{\"type\":\"image\",\"props\":{\"image\":\"app\\\/uploads\\\/2020\\\/03\\\/ZEDcontrol_front-1.png\",\"image_alt\":\"Die Auswerteeinheit ZEDcontrol zur Dichtheitspr\\u00fcfung mit Luft\",\"image_svg_color\":\"emphasis\",\"link\":\"de\\\/technologien\\\/dichtheitspruefung\\\/dichtheitspruefung-mit-luft\\\/zedflex\\\/#zedcontrol\",\"margin\":\"default\",\"text_align\":\"center\"}},{\"type\":\"button\",\"props\":{\"grid_column_gap\":\"small\",\"grid_row_gap\":\"small\",\"margin\":\"\",\"text_align\":\"center\"},\"children\":[{\"type\":\"button_item\",\"props\":{\"button_style\":\"\",\"content\":\"ZEDcontrol\",\"dialog_layout\":\"modal\",\"dialog_offcanvas_flip\":true,\"icon_align\":\"left\",\"link\":\"de\\\/technologien\\\/dichtheitspruefung\\\/dichtheitspruefung-mit-luft\\\/zedflex\\\/#zedcontrol\",\"link_title\":\"Link zu den Infos \\u00fcber ZEDcontrol auf der Produktseite ZEDflex\"}}]},{\"type\":\"text\",\"props\":{\"column_breakpoint\":\"m\",\"content\":\"\n\n<p>Die universelle 19\\u201c-Steuer- und Auswerteeinheit der ZEDflex f\\u00fcr bis zu acht Messmodule<\\\/p>\",\"margin\":\"default\",\"text_align\":\"center\"}}]},{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"position_sticky_breakpoint\":\"m\",\"vertical_align\":\"bottom\",\"width_small\":\"1-3\"},\"children\":[{\"type\":\"image\",\"props\":{\"image\":\"app\\\/uploads\\\/2020\\\/02\\\/ZEDcon.png\",\"image_alt\":\"Die Standardadapter ZEDcon zur Dichtheitspr\\u00fcfung mit Luft\",\"image_svg_color\":\"emphasis\",\"link\":\"de\\\/technologien\\\/dichtheitspruefung\\\/dichtheitspruefung-mit-luft\\\/zedcon\\\/\",\"margin\":\"default\",\"text_align\":\"center\"}},{\"type\":\"button\",\"props\":{\"grid_column_gap\":\"small\",\"grid_row_gap\":\"small\",\"margin\":\"\",\"text_align\":\"center\"},\"children\":[{\"type\":\"button_item\",\"props\":{\"button_style\":\"\",\"content\":\"ZEDcon\",\"dialog_layout\":\"modal\",\"dialog_offcanvas_flip\":true,\"icon_align\":\"left\",\"link\":\"de\\\/technologien\\\/dichtheitspruefung\\\/dichtheitspruefung-mit-luft\\\/zedcon\\\/\",\"link_title\":\"Link zur Produktseite ZEDcon\"}}]},{\"type\":\"text\",\"props\":{\"column_breakpoint\":\"m\",\"content\":\"\n\n<p>Die Standard-Adapterserie f\\u00fcr die Verbindung der ZED-Ger\\u00e4tefamilie mit dem Pr\\u00fcfling<\\\/p>\",\"margin\":\"default\",\"text_align\":\"center\"}}]},{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"position_sticky_breakpoint\":\"m\",\"vertical_align\":\"bottom\",\"width_small\":\"1-3\"},\"children\":[{\"type\":\"image\",\"props\":{\"image\":\"app\\\/uploads\\\/2020\\\/03\\\/ZEDnet_SplashScreen.png\",\"image_alt\":\"Die Softwarel\\u00f6sung ZEDnet zur Dichtheitspr\\u00fcfung mit Luft\",\"image_svg_color\":\"emphasis\",\"link\":\"de\\\/technologien\\\/dichtheitspruefung\\\/dichtheitspruefung-mit-luft\\\/zednet\\\/\",\"margin\":\"default\",\"text_align\":\"center\"}},{\"type\":\"button\",\"props\":{\"grid_column_gap\":\"small\",\"grid_row_gap\":\"small\",\"margin\":\"\",\"text_align\":\"center\"},\"children\":[{\"type\":\"button_item\",\"props\":{\"button_style\":\"\",\"content\":\"ZEDnet\",\"dialog_layout\":\"modal\",\"dialog_offcanvas_flip\":true,\"icon_align\":\"left\",\"link\":\"de\\\/technologien\\\/dichtheitspruefung\\\/dichtheitspruefung-mit-luft\\\/zednet\\\/\",\"link_title\":\"Link zur Produktseite ZEDnet\"}}]},{\"type\":\"text\",\"props\":{\"column_breakpoint\":\"m\",\"content\":\"\n\n<p>Die dezentrale Softwarel\\u00f6sung f\\u00fcr eine optimierte Verwaltung der ZED-Ger\\u00e4te<\\\/p>\",\"margin\":\"default\",\"text_align\":\"center\"}}]}]},{\"type\":\"row\",\"props\":{\"layout\":\"1-3,1-3,1-3\",\"margin\":\"medium\"},\"children\":[{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"position_sticky_breakpoint\":\"m\",\"vertical_align\":\"bottom\",\"width_small\":\"1-3\"},\"children\":[{\"type\":\"image\",\"props\":{\"image\":\"app\\\/uploads\\\/2020\\\/02\\\/ZW_Website-2020_Pruefleck_420x337px_R01-1.png\",\"image_alt\":\"Festleck zur Dichtheitspr\\u00fcfung mit Luft\",\"image_svg_color\":\"emphasis\",\"link\":\"de\\\/technologien\\\/dichtheitspruefung\\\/dichtheitspruefung-mit-luft\\\/pruefleck\\\/\",\"margin\":\"default\",\"text_align\":\"center\"}},{\"type\":\"button\",\"props\":{\"grid_column_gap\":\"small\",\"grid_row_gap\":\"small\",\"margin\":\"\",\"text_align\":\"center\"},\"children\":[{\"type\":\"button_item\",\"props\":{\"button_style\":\"\",\"content\":\"Zubeh\\u00f6r: Pr\\u00fcfleck\",\"dialog_layout\":\"modal\",\"dialog_offcanvas_flip\":true,\"icon_align\":\"left\",\"link\":\"de\\\/technologien\\\/dichtheitspruefung\\\/dichtheitspruefung-mit-luft\\\/pruefleck\\\/\",\"link_title\":\"Link zur Produktseite Pr\\u00fcfleck\"}}]},{\"type\":\"text\",\"props\":{\"column_breakpoint\":\"m\",\"content\":\"\n\n<p>Testleck zur \\u00dcberpr\\u00fcfung <br \\\/>und Parametrierung von Lecktest- und Dichtheitspr\\u00fcfger\\u00e4ten<\\\/p>\",\"margin\":\"default\",\"text_align\":\"center\"}}]},{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"position_sticky_breakpoint\":\"m\",\"vertical_align\":\"bottom\",\"width_small\":\"1-3\"},\"children\":[{\"type\":\"image\",\"props\":{\"image\":\"app\\\/uploads\\\/2020\\\/02\\\/ZW_Website-2020_Leckkalibrator_420x337px_R01-1.png\",\"image_alt\":\"Leckkalibrator zur Dichtheitspr\\u00fcfung mit Luft\",\"image_svg_color\":\"emphasis\",\"link\":\"de\\\/technologien\\\/dichtheitspruefung\\\/dichtheitspruefung-mit-luft\\\/leckkalibrator\\\/\",\"margin\":\"default\",\"text_align\":\"center\"}},{\"type\":\"button\",\"props\":{\"grid_column_gap\":\"small\",\"grid_row_gap\":\"small\",\"margin\":\"\",\"text_align\":\"center\"},\"children\":[{\"type\":\"button_item\",\"props\":{\"button_style\":\"\",\"content\":\"Zubeh\\u00f6r: Leckkalibrator\",\"dialog_layout\":\"modal\",\"dialog_offcanvas_flip\":true,\"icon_align\":\"left\",\"link\":\"de\\\/technologien\\\/dichtheitspruefung\\\/dichtheitspruefung-mit-luft\\\/leckkalibrator\\\/\",\"link_title\":\"Link zur Produktseite Leckkalibrator\"}}]},{\"type\":\"text\",\"props\":{\"column_breakpoint\":\"m\",\"content\":\"\n\n<p>Variables Testleck zur \\u00dcberpr\\u00fcfung und Parametrierung von Lecktest- und Dichtheitspr\\u00fcfger\\u00e4ten<\\\/p>\",\"margin\":\"default\",\"text_align\":\"center\"}}]},{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"position_sticky_breakpoint\":\"m\",\"vertical_align\":\"bottom\",\"width_small\":\"1-3\"}}]}],\"name\":\"ZED-Ger\\u00e4tefamilie\"},{\"type\":\"section\",\"props\":{\"css\":\" .el-section .uk-container-small {\\n    background-color: #003c8e;\\n}\\n\\n.el-section .uk-container {\\n     max-width: 780px;\\n}\\n\\n.el-section .uk-container {\\n     padding: 40px;\\n}\\n\",\"image_position\":\"center-center\",\"padding_remove_top\":false,\"style\":\"default\",\"title_breakpoint\":\"xl\",\"title_position\":\"top-left\",\"title_rotation\":\"left\",\"vertical_align\":\"\",\"width\":\"small\"},\"children\":[{\"type\":\"row\",\"props\":{\"margin\":\"medium\",\"margin_remove_bottom\":false},\"children\":[{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"position_sticky_breakpoint\":\"m\",\"text_color\":\"light\",\"width_medium\":\"1-1\"},\"children\":[{\"type\":\"headline\",\"props\":{\"content\":\"Beratung gew\\u00fcnscht?\",\"margin\":\"medium\",\"margin_remove_bottom\":false,\"text_align\":\"center\",\"title_element\":\"h2\",\"title_style\":\"heading-medium\"}}]}]},{\"type\":\"row\",\"props\":{\"layout\":\"1-2,1-2\"},\"children\":[{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"position_sticky_breakpoint\":\"m\",\"text_color\":\"light\",\"width_medium\":\"1-2\"},\"children\":[{\"type\":\"text\",\"props\":{\"column_breakpoint\":\"m\",\"content\":\"\n\n<p>Wir verstehen uns in erster Linie als Fachinstanz, Berater und enger Partner unserer Kunden. Gemeinsam ermitteln wir deshalb mit Ihnen den Pr\\u00fcfbedarf und die beste L\\u00f6sung.<\\\/p>\",\"css\":\".el-element p:last-child {\\n\\tmargin-bottom: 0;\\n}\",\"margin\":\"default\"}}]},{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"position_sticky_breakpoint\":\"m\",\"text_color\":\"light\",\"width_medium\":\"1-2\"},\"children\":[{\"type\":\"button\",\"props\":{\"grid_column_gap\":\"small\",\"grid_row_gap\":\"small\",\"margin\":\"default\",\"text_align\":\"right\"},\"children\":[{\"type\":\"button_item\",\"props\":{\"button_style\":\"primary\",\"content\":\"Kontaktieren Sie unseren Service\",\"dialog_layout\":\"modal\",\"dialog_offcanvas_flip\":true,\"icon_align\":\"left\",\"link\":\"de\\\/service\\\/dichtheitspruefung\\\/\",\"link_title\":\"Link zum Service Dichtheitspr\\u00fcfung\"}}]}]}]}],\"name\":\"Ansprechperson\"},{\"type\":\"section\",\"props\":{\"image_position\":\"center-center\",\"padding_remove_top\":true,\"style\":\"default\",\"title_breakpoint\":\"xl\",\"title_position\":\"top-left\",\"title_rotation\":\"left\",\"vertical_align\":\"\",\"width\":\"small\"},\"children\":[{\"type\":\"row\",\"props\":{\"margin\":\"medium\"},\"children\":[{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"position_sticky_breakpoint\":\"m\",\"width_medium\":\"1-1\"},\"children\":[{\"type\":\"headline\",\"props\":{\"content\":\"Qualit\\u00e4tssicherung ist unsere Kernkompetenz\",\"title_element\":\"h3\",\"title_style\":\"heading-medium\"}}]}]},{\"type\":\"row\",\"props\":{\"column_gap\":\"collapse\",\"layout\":\"1-2,1-2\",\"margin\":\"small\",\"row_gap\":\"collapse\"},\"children\":[{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"position_sticky_breakpoint\":\"m\",\"style\":\"tile-secondary\",\"vertical_align\":\"middle\",\"width_small\":\"1-2\"},\"children\":[{\"type\":\"headline\",\"props\":{\"content\":\"Das k\\u00f6nnen wir\",\"position\":\"relative\",\"title_element\":\"h2\",\"title_style\":\"heading-medium\"}}]},{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"position_sticky_breakpoint\":\"m\",\"style\":\"tile-secondary\",\"vertical_align\":\"middle\",\"width_small\":\"1-2\"},\"children\":[{\"type\":\"text\",\"props\":{\"column_breakpoint\":\"m\",\"content\":\"\n\n<p><a href=\\\"https:\\\/\\\/www.zeltwanger.de\\\/de\\\/unternehmen\\\/zeltwanger-dichtheitspruefung\\\/\\\">Mehr \\u00fcber ZELTWANGER Dichtheitspr\\u00fcfung<\\\/a><\\\/p>\",\"css\":\".el-element p {\\n\\tmargin-bottom: 0;\\n}\",\"margin\":\"default\",\"position_right\":\"0\",\"position_top\":\"20px\",\"text_align\":\"right\",\"text_align_breakpoint\":\"s\"}}]}]},{\"type\":\"row\",\"props\":{\"layout\":\"1-2,1-2\"},\"children\":[{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"position_sticky_breakpoint\":\"m\",\"style\":\"tile-secondary\",\"width_medium\":\"1-2\"},\"children\":[{\"type\":\"headline\",\"props\":{\"content\":\"Pr\\u00fcfen mit Luft\",\"title_element\":\"h2\",\"title_style\":\"heading-medium\"}},{\"type\":\"text\",\"props\":{\"column_breakpoint\":\"m\",\"content\":\"\n\n<p>Durchfluss und Druck\\u00e4nderung \\u2013 f\\u00fcr diese Verfahren sind wir Spezialisten<\\\/p>\",\"margin\":\"default\"}},{\"type\":\"text\",\"props\":{\"column_breakpoint\":\"m\",\"content\":\"\n\n<p><a href=\\\"https:\\\/\\\/www.zeltwanger.de\\\/de\\\/technologien\\\/dichtheitspruefung\\\/dichtheitspruefung-mit-luft\\\/dichtheitspruefverfahren-mit-luft\\\/\\\">Dichtheitspr\\u00fcfverfahren mit Luft<\\\/a><\\\/p>\",\"margin\":\"default\"},\"name\":\"Link\"}]},{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"position_sticky_breakpoint\":\"m\",\"style\":\"tile-secondary\",\"width_medium\":\"1-2\"},\"children\":[{\"type\":\"headline\",\"props\":{\"content\":\"Pr\\u00fcfen mit Nachweisgasen\",\"title_element\":\"h2\",\"title_style\":\"heading-medium\"}},{\"type\":\"text\",\"props\":{\"column_breakpoint\":\"m\",\"content\":\"\n\n<p>Mit Helium und anderen Nachweisgasen kleinste Lecks finden<\\\/p>\",\"margin\":\"default\"}},{\"type\":\"text\",\"props\":{\"column_breakpoint\":\"m\",\"content\":\"\n\n<p><a href=\\\"https:\\\/\\\/www.zeltwanger.de\\\/de\\\/technologien\\\/dichtheitspruefung\\\/dichtheitspruefung-mit-nachweisgasen\\\/\\\">Dichtheitspr\\u00fcfung mit Nachweisgasen<\\\/a><\\\/p>\",\"margin\":\"default\"},\"name\":\"Link\"}]}]}],\"name\":\"CTA Graue Kacheln\"},{\"type\":\"section\",\"props\":{\"id\":\"flyout\",\"image_position\":\"center-center\",\"style\":\"default\",\"title_breakpoint\":\"xl\",\"title_position\":\"top-left\",\"title_rotation\":\"left\",\"vertical_align\":\"\",\"width\":\"default\"},\"children\":[{\"type\":\"row\",\"children\":[{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"position_sticky_breakpoint\":\"m\",\"width_medium\":\"1-1\"},\"children\":[{\"type\":\"flyout\",\"props\":{\"content_title\":\"Noch fragen?\",\"flyout_button_text\":\"Kontaktieren Sie uns\",\"parent\":\"flyout\",\"show_content_title\":true,\"show_image\":true},\"children\":[{\"type\":\"flyout_item\",\"props\":{\"name_text\":\"20899\",\"post_id\":20899}},{\"type\":\"flyout_item\",\"props\":{\"name_text\":\"20900\",\"post_id\":20900}}]}]}]}],\"name\":\"Ansprechperson Flyout\"}],\"version\":\"4.5.11\"} --><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dichtheitspr\u00fcfung mit Luft Maximal flexibel mit der ZED-Ger\u00e4tefamilie Eine verl\u00e4ssliche Qualit\u00e4tssicherung hat immer Vorrang. Gleichzeitig gilt, dass sich Dichtheitspr\u00fcfung mit Luft leicht in Produktionsabl\u00e4ufe integrieren lassen muss, wenn sie wirtschaftlich sein soll. Daf\u00fcr sorgen wir mit den ZED Dichtheitspr\u00fcfger\u00e4ten. Ob kleines, mobiles Dichtheitspr\u00fcfger\u00e4t oder teilautomatisierte Pr\u00fcfstation \u2013 die ZED-Ger\u00e4tefamilie zeichnet sich durch maximale Flexibilit\u00e4t in [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":0,"parent":1745,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-1790","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Dichtheitspr\u00fcfung mit Luft | Wir sind die Spezialisten<\/title>\n<meta name=\"description\" content=\"Erfolgreiche Dichtheitspr\u00fcfung mit Luft | ZED-Ger\u00e4tefamilie \u2013 F\u00fcr jede Anforderung das passende Ger\u00e4t | Analyse \u2022 Adaptionen \u2022 Service \u2022 Schulungen\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.zeltwanger.de\/de\/technologien\/dichtheitspruefung\/dichtheitspruefung-mit-luft\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dichtheitspr\u00fcfung mit Luft | Wir sind die Spezialisten\" \/>\n<meta property=\"og:description\" content=\"Erfolgreiche Dichtheitspr\u00fcfung mit Luft | ZED-Ger\u00e4tefamilie \u2013 F\u00fcr jede Anforderung das passende Ger\u00e4t | Analyse \u2022 Adaptionen \u2022 Service \u2022 Schulungen\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.zeltwanger.de\/de\/technologien\/dichtheitspruefung\/dichtheitspruefung-mit-luft\/\" \/>\n<meta property=\"og:site_name\" content=\"ZELTWANGER\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/zeltwanger.karriere\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-16T13:15:21+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.zeltwanger.de\\\/de\\\/technologien\\\/dichtheitspruefung\\\/dichtheitspruefung-mit-luft\\\/\",\"url\":\"https:\\\/\\\/www.zeltwanger.de\\\/de\\\/technologien\\\/dichtheitspruefung\\\/dichtheitspruefung-mit-luft\\\/\",\"name\":\"Dichtheitspr\u00fcfung mit Luft | Wir sind die Spezialisten\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.zeltwanger.de\\\/de\\\/#website\"},\"datePublished\":\"2020-01-22T13:46:52+00:00\",\"dateModified\":\"2025-06-16T13:15:21+00:00\",\"description\":\"Erfolgreiche Dichtheitspr\u00fcfung mit Luft | ZED-Ger\u00e4tefamilie \u2013 F\u00fcr jede Anforderung das passende Ger\u00e4t | Analyse \u2022 Adaptionen \u2022 Service \u2022 Schulungen\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.zeltwanger.de\\\/de\\\/technologien\\\/dichtheitspruefung\\\/dichtheitspruefung-mit-luft\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.zeltwanger.de\\\/de\\\/technologien\\\/dichtheitspruefung\\\/dichtheitspruefung-mit-luft\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.zeltwanger.de\\\/de\\\/technologien\\\/dichtheitspruefung\\\/dichtheitspruefung-mit-luft\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.zeltwanger.de\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Technologien\",\"item\":\"https:\\\/\\\/www.zeltwanger.de\\\/de\\\/technologien\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"L\u00f6sungen f\u00fcr die Dichtheitspr\u00fcfung\",\"item\":\"https:\\\/\\\/www.zeltwanger.de\\\/de\\\/technologien\\\/dichtheitspruefung\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Dichtheitspr\u00fcfung mit Luft\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.zeltwanger.de\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.zeltwanger.de\\\/de\\\/\",\"name\":\"ZELTWANGER\",\"description\":\"Innovation aus Freude an Technik\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.zeltwanger.de\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.zeltwanger.de\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.zeltwanger.de\\\/de\\\/#organization\",\"name\":\"ZELTWANGER\",\"url\":\"https:\\\/\\\/www.zeltwanger.de\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.zeltwanger.de\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.zeltwanger.de\\\/app\\\/uploads\\\/2024\\\/03\\\/ZELTWANGER-Maennchen_nebeneinander_RGB_Screen_quadratisch_klein-e1710331495893.jpg\",\"contentUrl\":\"https:\\\/\\\/www.zeltwanger.de\\\/app\\\/uploads\\\/2024\\\/03\\\/ZELTWANGER-Maennchen_nebeneinander_RGB_Screen_quadratisch_klein-e1710331495893.jpg\",\"width\":144,\"height\":144,\"caption\":\"ZELTWANGER\"},\"image\":{\"@id\":\"https:\\\/\\\/www.zeltwanger.de\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/zeltwanger.karriere\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/11844117\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dichtheitspr\u00fcfung mit Luft | Wir sind die Spezialisten","description":"Erfolgreiche Dichtheitspr\u00fcfung mit Luft | ZED-Ger\u00e4tefamilie \u2013 F\u00fcr jede Anforderung das passende Ger\u00e4t | Analyse \u2022 Adaptionen \u2022 Service \u2022 Schulungen","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.zeltwanger.de\/de\/technologien\/dichtheitspruefung\/dichtheitspruefung-mit-luft\/","og_locale":"de_DE","og_type":"article","og_title":"Dichtheitspr\u00fcfung mit Luft | Wir sind die Spezialisten","og_description":"Erfolgreiche Dichtheitspr\u00fcfung mit Luft | ZED-Ger\u00e4tefamilie \u2013 F\u00fcr jede Anforderung das passende Ger\u00e4t | Analyse \u2022 Adaptionen \u2022 Service \u2022 Schulungen","og_url":"https:\/\/www.zeltwanger.de\/de\/technologien\/dichtheitspruefung\/dichtheitspruefung-mit-luft\/","og_site_name":"ZELTWANGER","article_publisher":"https:\/\/www.facebook.com\/zeltwanger.karriere\/","article_modified_time":"2025-06-16T13:15:21+00:00","twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.zeltwanger.de\/de\/technologien\/dichtheitspruefung\/dichtheitspruefung-mit-luft\/","url":"https:\/\/www.zeltwanger.de\/de\/technologien\/dichtheitspruefung\/dichtheitspruefung-mit-luft\/","name":"Dichtheitspr\u00fcfung mit Luft | Wir sind die Spezialisten","isPartOf":{"@id":"https:\/\/www.zeltwanger.de\/de\/#website"},"datePublished":"2020-01-22T13:46:52+00:00","dateModified":"2025-06-16T13:15:21+00:00","description":"Erfolgreiche Dichtheitspr\u00fcfung mit Luft | ZED-Ger\u00e4tefamilie \u2013 F\u00fcr jede Anforderung das passende Ger\u00e4t | Analyse \u2022 Adaptionen \u2022 Service \u2022 Schulungen","breadcrumb":{"@id":"https:\/\/www.zeltwanger.de\/de\/technologien\/dichtheitspruefung\/dichtheitspruefung-mit-luft\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.zeltwanger.de\/de\/technologien\/dichtheitspruefung\/dichtheitspruefung-mit-luft\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.zeltwanger.de\/de\/technologien\/dichtheitspruefung\/dichtheitspruefung-mit-luft\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.zeltwanger.de\/de\/"},{"@type":"ListItem","position":2,"name":"Technologien","item":"https:\/\/www.zeltwanger.de\/de\/technologien\/"},{"@type":"ListItem","position":3,"name":"L\u00f6sungen f\u00fcr die Dichtheitspr\u00fcfung","item":"https:\/\/www.zeltwanger.de\/de\/technologien\/dichtheitspruefung\/"},{"@type":"ListItem","position":4,"name":"Dichtheitspr\u00fcfung mit Luft"}]},{"@type":"WebSite","@id":"https:\/\/www.zeltwanger.de\/de\/#website","url":"https:\/\/www.zeltwanger.de\/de\/","name":"ZELTWANGER","description":"Innovation aus Freude an Technik","publisher":{"@id":"https:\/\/www.zeltwanger.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.zeltwanger.de\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.zeltwanger.de\/de\/#organization","name":"ZELTWANGER","url":"https:\/\/www.zeltwanger.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.zeltwanger.de\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.zeltwanger.de\/app\/uploads\/2024\/03\/ZELTWANGER-Maennchen_nebeneinander_RGB_Screen_quadratisch_klein-e1710331495893.jpg","contentUrl":"https:\/\/www.zeltwanger.de\/app\/uploads\/2024\/03\/ZELTWANGER-Maennchen_nebeneinander_RGB_Screen_quadratisch_klein-e1710331495893.jpg","width":144,"height":144,"caption":"ZELTWANGER"},"image":{"@id":"https:\/\/www.zeltwanger.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/zeltwanger.karriere\/","https:\/\/www.linkedin.com\/company\/11844117\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.zeltwanger.de\/de\/wp-json\/wp\/v2\/pages\/1790","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.zeltwanger.de\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.zeltwanger.de\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.zeltwanger.de\/de\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.zeltwanger.de\/de\/wp-json\/wp\/v2\/comments?post=1790"}],"version-history":[{"count":261,"href":"https:\/\/www.zeltwanger.de\/de\/wp-json\/wp\/v2\/pages\/1790\/revisions"}],"predecessor-version":[{"id":33671,"href":"https:\/\/www.zeltwanger.de\/de\/wp-json\/wp\/v2\/pages\/1790\/revisions\/33671"}],"up":[{"embeddable":true,"href":"https:\/\/www.zeltwanger.de\/de\/wp-json\/wp\/v2\/pages\/1745"}],"wp:attachment":[{"href":"https:\/\/www.zeltwanger.de\/de\/wp-json\/wp\/v2\/media?parent=1790"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}